{"id":86083,"date":"2014-08-26T16:14:05","date_gmt":"2014-08-26T23:14:05","guid":{"rendered":"http:\/\/old.newsforchinese.com\/v3\/?p=86083"},"modified":"2014-08-26T16:14:05","modified_gmt":"2014-08-26T23:14:05","slug":"%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1","status":"publish","type":"post","link":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/","title":{"rendered":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031"},"content":{"rendered":"<p><span style=\"color: #000000;\">\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c<!--more-->\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002<\/span><br style=\"color: #000000;\" \/><br style=\"color: #000000;\" \/><span style=\"color: #000000;\">\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002<\/span><\/p>\n<p>\u6587\/\u4e2d\u592e\u793e<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"news\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1409069645\"\r\n\t            data-title=\"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031\" \r\n\t            data-home=\"https:\/\/newsforchinese.com\/v3\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c<\/p>\n","protected":false},"author":1,"featured_media":86082,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[131],"tags":[],"series":[],"class_list":["post-86083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Raymond\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<meta name=\"google-adsense-account\" content=\"ca-pub-9175855296033541\">\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19 - \u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19\" \/>\n\t\t<meta property=\"og:description\" content=\"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t\t<meta property=\"og:image:height\" content=\"332\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-08-26T23:14:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-08-26T23:14:05+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#blogposting\",\"name\":\"\\u9ec3\\u8272\\u5c0f\\u9d28\\u98a8\\u9761\\u6d1b\\u57ce \\u5ef6\\u5c55\\u5169\\u9031 - News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"headline\":\"\\u9ec3\\u8272\\u5c0f\\u9d28\\u98a8\\u9761\\u6d1b\\u57ce \\u5ef6\\u5c55\\u5169\\u9031\",\"author\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/laoho\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/yellow-duck.jpg\",\"width\":600,\"height\":332},\"datePublished\":\"2014-08-26T16:14:05-07:00\",\"dateModified\":\"2014-08-26T16:14:05-07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#webpage\"},\"articleSection\":\"\\u7f8e\\u570b\\u65b0\\u805e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newsforchinese.com\\\/v3\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/news\\\/#listItem\",\"name\":\"\\u7f8e\\u570b\\u65b0\\u805e\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/news\\\/#listItem\",\"position\":2,\"name\":\"\\u7f8e\\u570b\\u65b0\\u805e\",\"item\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#listItem\",\"name\":\"\\u9ec3\\u8272\\u5c0f\\u9d28\\u98a8\\u9761\\u6d1b\\u57ce \\u5ef6\\u5c55\\u5169\\u9031\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#listItem\",\"position\":3,\"name\":\"\\u9ec3\\u8272\\u5c0f\\u9d28\\u98a8\\u9761\\u6d1b\\u57ce \\u5ef6\\u5c55\\u5169\\u9031\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/news\\\/#listItem\",\"name\":\"\\u7f8e\\u570b\\u65b0\\u805e\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#organization\",\"name\":\"News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"description\":\"\\u8001\\u4e2d\\u5730\\u65b9\\u65b0\\u805e\\u662f\\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u65b0\\u805e\\u96c6\\u5718\\uff0c\\u591a\\u5143\\u5316\\u5e73\\u53f0\\u6709\\u65b0\\u805e\\u7db2\\u3001\\u5f71\\u97f3\\u7db2\\u3001AM1450\\u5ee3\\u64ad\\u96fb\\u53f0\\u53ca\\u514d\\u8cbb\\u5168\\u5f69\\u5831\\u7d19\\u3002\\u624b\\u6a5f\\u63d0\\u4f9b\\u6700\\u65b0\\u6700\\u5feb\\u793e\\u5340\\u65b0\\u805e\\uff0c\\u670d\\u52d960\\u842c\\u83ef\\u88d4\\u8b80\\u8005\\u3002\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/laoho\\\/#author\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/laoho\\\/\",\"name\":\"Raymond\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/933050d3bba711ae8eed7fe05532e2ceec7ca7198723c94bd86c205bf099f7a2?s=96&d=retro&r=g\",\"width\":96,\"height\":96,\"caption\":\"Raymond\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#webpage\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/\",\"name\":\"\\u9ec3\\u8272\\u5c0f\\u9d28\\u98a8\\u9761\\u6d1b\\u57ce \\u5ef6\\u5c55\\u5169\\u9031 - News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"description\":\"\\u9ec3\\u8272\\u5c0f\\u9d28\\u98a8\\u9761\\u5168\\u7403\\uff0c\\u6d1b\\u6749\\u78ef\\u4e5f\\u4e0d\\u4f8b\\u5916\\u3002\\u5728\\u6d1b\\u6749\\u78ef\\u6e2f\\u76845\\u5929\\u5c55\\u671f\\uff0c\\u4f30\\u8a08\\u5438\\u5f15\\u4e86\\u8d85\\u904e33\\u842c\\u4eba\\u6b21\\u89c0\\u8cde\\uff0c\\u70ba\\u4e86\\u8b93\\u66f4\\u591a\\u4eba\\u6709\\u6b23\\u8cde\\u7684\\u6a5f\\u6703\\uff0c\\u6d1b\\u6749\\u78ef\\u6e2f\\u5c07\\u5c55\\u671f\\u5ef6\\u9577\\u5169\\u500b\\u661f\\u671f\\u3002\\u9019\\u96bb\\u865f\\u7a31\\u5168\\u4e16\\u754c\\u6700\\u5927\\u7684\\u9ec3\\u8272\\u5c0f\\u9d28\\uff0c\\u9ad861\\u544e\\u3001\\u5bec85\\u544e\\u3001\\u9577110\\u544e\\uff0c\\u904e\\u53bb5\\u5929\\u5728\\u6d1b\\u6749\\u78ef\\u6e2f\\u914d\\u5408\\u9ad8\\u6845\\u5e06\\u8239\\u7bc0\\u5609\\u5e74\\u83ef\\u6703\\u5c55\\u51fa\\uff0c\\u539f\\u5b9a\\u6628\\u5929\\u843d\\u5e55\\u3002\\u7531\\u65bc\\u53c3\\u89c0\\u7684\\u4eba\\u6578\\u5be6\\u5728\\u592a\\u591a\\uff0c\\u6d1b\\u6749\\u78ef\\u6e2f\\u6c7a\\u5b9a\\u52a0\\u8fa6\\u300c\\u590f\\u65e5\\u5c0f\\u9d28\\u65e5\\u300d\\u6d3b\\u52d5\\uff0c\\u5c07\\u9ec3\\u8272\\u5c0f\\u9d28\\u7684\\u5c55\\u671f\\u5ef6\\u9577\\u5169\\u500b\\u661f\\u671f\\uff0c\\u6eff\\u8db3\\u66f4\\u591a\\u6c11\\u773e\\u60f3\\u770b\\u9ec3\\u8272\\u5c0f\\u9d28\\u7684\\u9858\\u671b\\u3002\\u904e\\u53bb5\\u5929\\u4f86\\uff0c\\u96d6\\u7136\\u6c92\\u6709\\u5b98\\u65b9\\u7684\\u6578\\u5b57\\u7d71\\u8a08\\uff0c\\u4f46\\u9ad8\\u6845\\u5e06\\u8239\\u7bc0\\u7684\\u4e3b\\u8fa6\\u55ae\\u4f4d\\u4f30\\u8a08\\uff0c\\u5171\\u6709\\u591a\\u905433\\u842c\\u4eba\\u6b21\\u89c0\\u8cde\\uff0c\\u904e\\u53bb\\u5169\\u5929\\u5468\\u672b\\u5047\\u671f\\uff0c\\u5c31\\u6e67\\u9032\\u4e86\\u8fd125\\u842c\\u4eba\\u6b21\\uff0c\\u5c07\\u6d1b\\u6749\\u78ef\\u6e2f\\u5468\\u908a\\u9053\\u8def\\u64e0\\u5f97\\u6c34\\u6d29\\u4e0d\\u901a\\uff0c\\u751a\\u81f3\\u9084\\u56de\\u5835\\u5230\\u9ad8\\u901f\\u516c\\u8def\\uff0c\\u53ef\\u898b\\u9ec3\\u8272\\u5c0f\\u9d28\\u7684\\u53d7\\u6b61\\u8fce\\u7a0b\\u5ea6\\u3002\\u6d1b\\u6749\\u78ef\\u6e2f\\u767c\\u8a00\\u4eba\\u6851\\u83f2\\u723e\\u5fb7\\uff08Phillip Sanfield\\uff09\\u8aaa\\uff0c\\u4ed6\\u5011\\u671f\\u76fc\\u66f4\\u591a\\u4eba\\u53ef\\u4ee5\\u770b\\u5230\\u9ec3\\u8272\\u5c0f\\u9d28\\uff0c\\u4f46\\u5728\\u63a5\\u4e0b\\u4f86\\u7684\\u5169\\u500b\\u661f\\u671f\\uff0c\\u6bcf\\u5929\\u90fd\\u6703\\u6709\\u4e9b\\u8a31\\u7684\\u4e0d\\u540c\\u3002\\u4eca\\u5929\\u662f\\u570b\\u969b\\u9d28\\u5b50\\u65e5\\uff0c\\u6d1b\\u6749\\u78ef\\u6e2f\\u8b93\\u9ec3\\u8272\\u5c0f\\u9d28\\u56de\\u5230\\u539f\\u672c\\u7684\\u5c55\\u89bd\\u5730\\u9ede\\uff0c\\u4e0d\\u904e\\u9019\\u500b\\u661f\\u671f\\u9069\\u9022\\u52de\\u52d5\\u7bc0\\u5047\\u671f\\uff0c\\u6d1b\\u6749\\u78ef\\u6e2f\\u4e5f\\u8b93\\u9ec3\\u8272\\u5c0f\\u9d28\\u4f11\\u5047\\uff0c\\u7b49\\u5230\\u5047\\u671f\\u7d50\\u675f\\u4e4b\\u5f8c\\uff0c\\u9ec3\\u8272\\u5c0f\\u9d28\\u5c31\\u6703\\u91cd\\u65b0\\u56de\\u5230\\u5de5\\u4f5c\\u5d17\\u4f4d\\u3002\\u6d1b\\u6749\\u78ef\\u6e2f\\u4e5f\\u7b56\\u5283\\u4e86\\u8a31\\u591a\\u4e3b\\u984c\\uff0c\\u5305\\u62ec\\u300c\\u7a7f\\u8457\\u50cf\\u96bb\\u9d28\\u5b50\\u65e5\\u300d\\u3001\\u300c\\u9d28\\u5b50\\u821e\\u65e5\\u300d\\u3001\\u300c\\u5e74\\u8f15\\u9d28\\u5b50\\u65e5\\u300d\\u7b49\\u7b49\\uff0c\\u914d\\u5408\\u5404\\u5f0f\\u4e3b\\u984c\\u898f\\u5283\\u4e0d\\u540c\\u7684\\u6d3b\\u52d5\\uff0c\\u8b93\\u66f4\\u591a\\u6c11\\u773e\\u53ef\\u4ee5\\u8207\\u9ec3\\u8272\\u5c0f\\u9d28\\u540c\\u6a02\\u3002 \\u6587\\\/\\u4e2d\\u592e\\u793e\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/laoho\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/laoho\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/wp-content\\\/uploads\\\/2014\\\/08\\\/yellow-duck.jpg\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#mainImage\",\"width\":600,\"height\":332},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2014\\\/08\\\/26\\\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\\\/#mainImage\"},\"datePublished\":\"2014-08-26T16:14:05-07:00\",\"dateModified\":\"2014-08-26T16:14:05-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/\",\"name\":\"News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"description\":\"\\u8001\\u4e2d\\u5730\\u65b9\\u65b0\\u805e\\u662f\\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u65b0\\u805e\\u96c6\\u5718\\uff0c\\u591a\\u5143\\u5316\\u5e73\\u53f0\\u6709\\u65b0\\u805e\\u7db2\\u3001\\u5f71\\u97f3\\u7db2\\u3001AM1450\\u5ee3\\u64ad\\u96fb\\u53f0\\u53ca\\u514d\\u8cbb\\u5168\\u5f69\\u5831\\u7d19\\u3002\\u624b\\u6a5f\\u63d0\\u4f9b\\u6700\\u65b0\\u6700\\u5feb\\u793e\\u5340\\u65b0\\u805e\\uff0c\\u670d\\u52d960\\u842c\\u83ef\\u88d4\\u8b80\\u8005\\u3002\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e","canonical_url":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;meta name=\"google-adsense-account\" content=\"ca-pub-9175855296033541\"&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#blogposting","name":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","headline":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031","author":{"@id":"https:\/\/newsforchinese.com\/v3\/author\/laoho\/#author"},"publisher":{"@id":"https:\/\/newsforchinese.com\/v3\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg","width":600,"height":332},"datePublished":"2014-08-26T16:14:05-07:00","dateModified":"2014-08-26T16:14:05-07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#webpage"},"isPartOf":{"@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#webpage"},"articleSection":"\u7f8e\u570b\u65b0\u805e"},{"@type":"BreadcrumbList","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3#listItem","position":1,"name":"Home","item":"https:\/\/newsforchinese.com\/v3","nextItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/category\/news\/#listItem","name":"\u7f8e\u570b\u65b0\u805e"}},{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/category\/news\/#listItem","position":2,"name":"\u7f8e\u570b\u65b0\u805e","item":"https:\/\/newsforchinese.com\/v3\/category\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#listItem","name":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031"},"previousItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#listItem","position":3,"name":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031","previousItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/category\/news\/#listItem","name":"\u7f8e\u570b\u65b0\u805e"}}]},{"@type":"Organization","@id":"https:\/\/newsforchinese.com\/v3\/#organization","name":"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002","url":"https:\/\/newsforchinese.com\/v3\/"},{"@type":"Person","@id":"https:\/\/newsforchinese.com\/v3\/author\/laoho\/#author","url":"https:\/\/newsforchinese.com\/v3\/author\/laoho\/","name":"Raymond","image":{"@type":"ImageObject","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/933050d3bba711ae8eed7fe05532e2ceec7ca7198723c94bd86c205bf099f7a2?s=96&d=retro&r=g","width":96,"height":96,"caption":"Raymond"}},{"@type":"WebPage","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#webpage","url":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/","name":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/newsforchinese.com\/v3\/#website"},"breadcrumb":{"@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#breadcrumblist"},"author":{"@id":"https:\/\/newsforchinese.com\/v3\/author\/laoho\/#author"},"creator":{"@id":"https:\/\/newsforchinese.com\/v3\/author\/laoho\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg","@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#mainImage","width":600,"height":332},"primaryImageOfPage":{"@id":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/#mainImage"},"datePublished":"2014-08-26T16:14:05-07:00","dateModified":"2014-08-26T16:14:05-07:00"},{"@type":"WebSite","@id":"https:\/\/newsforchinese.com\/v3\/#website","url":"https:\/\/newsforchinese.com\/v3\/","name":"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002","inLanguage":"en-US","publisher":{"@id":"https:\/\/newsforchinese.com\/v3\/#organization"}}]},"og:locale":"en_US","og:site_name":"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19 - \u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002","og:type":"article","og:title":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","og:description":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e","og:url":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/","og:image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg","og:image:secure_url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg","og:image:width":600,"og:image:height":332,"article:published_time":"2014-08-26T23:14:05+00:00","article:modified_time":"2014-08-26T23:14:05+00:00","twitter:card":"summary_large_image","twitter:title":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031 - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","twitter:description":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u5168\u7403\uff0c\u6d1b\u6749\u78ef\u4e5f\u4e0d\u4f8b\u5916\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u76845\u5929\u5c55\u671f\uff0c\u4f30\u8a08\u5438\u5f15\u4e86\u8d85\u904e33\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u70ba\u4e86\u8b93\u66f4\u591a\u4eba\u6709\u6b23\u8cde\u7684\u6a5f\u6703\uff0c\u6d1b\u6749\u78ef\u6e2f\u5c07\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\u3002\u9019\u96bb\u865f\u7a31\u5168\u4e16\u754c\u6700\u5927\u7684\u9ec3\u8272\u5c0f\u9d28\uff0c\u9ad861\u544e\u3001\u5bec85\u544e\u3001\u9577110\u544e\uff0c\u904e\u53bb5\u5929\u5728\u6d1b\u6749\u78ef\u6e2f\u914d\u5408\u9ad8\u6845\u5e06\u8239\u7bc0\u5609\u5e74\u83ef\u6703\u5c55\u51fa\uff0c\u539f\u5b9a\u6628\u5929\u843d\u5e55\u3002\u7531\u65bc\u53c3\u89c0\u7684\u4eba\u6578\u5be6\u5728\u592a\u591a\uff0c\u6d1b\u6749\u78ef\u6e2f\u6c7a\u5b9a\u52a0\u8fa6\u300c\u590f\u65e5\u5c0f\u9d28\u65e5\u300d\u6d3b\u52d5\uff0c\u5c07\u9ec3\u8272\u5c0f\u9d28\u7684\u5c55\u671f\u5ef6\u9577\u5169\u500b\u661f\u671f\uff0c\u6eff\u8db3\u66f4\u591a\u6c11\u773e\u60f3\u770b\u9ec3\u8272\u5c0f\u9d28\u7684\u9858\u671b\u3002\u904e\u53bb5\u5929\u4f86\uff0c\u96d6\u7136\u6c92\u6709\u5b98\u65b9\u7684\u6578\u5b57\u7d71\u8a08\uff0c\u4f46\u9ad8\u6845\u5e06\u8239\u7bc0\u7684\u4e3b\u8fa6\u55ae\u4f4d\u4f30\u8a08\uff0c\u5171\u6709\u591a\u905433\u842c\u4eba\u6b21\u89c0\u8cde\uff0c\u904e\u53bb\u5169\u5929\u5468\u672b\u5047\u671f\uff0c\u5c31\u6e67\u9032\u4e86\u8fd125\u842c\u4eba\u6b21\uff0c\u5c07\u6d1b\u6749\u78ef\u6e2f\u5468\u908a\u9053\u8def\u64e0\u5f97\u6c34\u6d29\u4e0d\u901a\uff0c\u751a\u81f3\u9084\u56de\u5835\u5230\u9ad8\u901f\u516c\u8def\uff0c\u53ef\u898b\u9ec3\u8272\u5c0f\u9d28\u7684\u53d7\u6b61\u8fce\u7a0b\u5ea6\u3002\u6d1b\u6749\u78ef\u6e2f\u767c\u8a00\u4eba\u6851\u83f2\u723e\u5fb7\uff08Phillip Sanfield\uff09\u8aaa\uff0c\u4ed6\u5011\u671f\u76fc\u66f4\u591a\u4eba\u53ef\u4ee5\u770b\u5230\u9ec3\u8272\u5c0f\u9d28\uff0c\u4f46\u5728\u63a5\u4e0b\u4f86\u7684\u5169\u500b\u661f\u671f\uff0c\u6bcf\u5929\u90fd\u6703\u6709\u4e9b\u8a31\u7684\u4e0d\u540c\u3002\u4eca\u5929\u662f\u570b\u969b\u9d28\u5b50\u65e5\uff0c\u6d1b\u6749\u78ef\u6e2f\u8b93\u9ec3\u8272\u5c0f\u9d28\u56de\u5230\u539f\u672c\u7684\u5c55\u89bd\u5730\u9ede\uff0c\u4e0d\u904e\u9019\u500b\u661f\u671f\u9069\u9022\u52de\u52d5\u7bc0\u5047\u671f\uff0c\u6d1b\u6749\u78ef\u6e2f\u4e5f\u8b93\u9ec3\u8272\u5c0f\u9d28\u4f11\u5047\uff0c\u7b49\u5230\u5047\u671f\u7d50\u675f\u4e4b\u5f8c\uff0c\u9ec3\u8272\u5c0f\u9d28\u5c31\u6703\u91cd\u65b0\u56de\u5230\u5de5\u4f5c\u5d17\u4f4d\u3002\u6d1b\u6749\u78ef\u6e2f\u4e5f\u7b56\u5283\u4e86\u8a31\u591a\u4e3b\u984c\uff0c\u5305\u62ec\u300c\u7a7f\u8457\u50cf\u96bb\u9d28\u5b50\u65e5\u300d\u3001\u300c\u9d28\u5b50\u821e\u65e5\u300d\u3001\u300c\u5e74\u8f15\u9d28\u5b50\u65e5\u300d\u7b49\u7b49\uff0c\u914d\u5408\u5404\u5f0f\u4e3b\u984c\u898f\u5283\u4e0d\u540c\u7684\u6d3b\u52d5\uff0c\u8b93\u66f4\u591a\u6c11\u773e\u53ef\u4ee5\u8207\u9ec3\u8272\u5c0f\u9d28\u540c\u6a02\u3002 \u6587\/\u4e2d\u592e\u793e","twitter:image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg"},"aioseo_meta_data":{"post_id":"86083","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-07-26 09:43:35","updated":"2025-06-08 05:51:38","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/newsforchinese.com\/v3\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/newsforchinese.com\/v3\/category\/news\/\" title=\"\u7f8e\u570b\u65b0\u805e\">\u7f8e\u570b\u65b0\u805e<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/newsforchinese.com\/v3"},{"label":"\u7f8e\u570b\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/news\/"},{"label":"\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031","link":"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/"}],"featured_image_urls":{"thumbnail":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck-150x150.jpg","medium":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck-300x166.jpg","single_img":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck-150x150.jpg"},"appp_media":null,"episode_featured_image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg","episode_player_image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2022\/11\/avatars-DFF30y5My1u3eZvX-2nXMSw-original.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/newsforchinese.com\/v3\/feed\/podcast\/%e8%80%81%e4%b8%ad%e5%bb%a3%e6%92%ad%e9%9b%bb%e5%8f%b0","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"RStZTPSaiL\"><a href=\"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/\">\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/newsforchinese.com\/v3\/2014\/08\/26\/%e9%bb%83%e8%89%b2%e5%b0%8f%e9%b4%a8%e9%a2%a8%e9%9d%a1%e6%b4%9b%e5%9f%8e-%e5%bb%b6%e5%b1%95%e5%85%a9%e9%80%b1\/embed\/#?secret=RStZTPSaiL\" width=\"500\" height=\"350\" title=\"&#8220;\u9ec3\u8272\u5c0f\u9d28\u98a8\u9761\u6d1b\u57ce \u5ef6\u5c55\u5169\u9031&#8221; &#8212; News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19\" data-secret=\"RStZTPSaiL\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/newsforchinese.com\/v3\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":121807,"url":"https:\/\/newsforchinese.com\/v3\/2016\/06\/28\/%e8%ad%a6%e5%93%a1%e6%ba%ab%e9%a6%a8%e7%95%ab%e9%9d%a2%ef%bc%9a%e6%90%b6%e6%95%91%e5%b0%8f%e9%b4%a8%e5%ad%90\/","url_meta":{"origin":86083,"position":0},"title":"\u8b66\u54e1\u6eab\u99a8\u756b\u9762\uff1a\u6436\u6551\u5c0f\u9d28\u5b50","author":"Raymond","date":"June 28, 2016","format":false,"excerpt":"Walnut\u00a0Creek\u57ce\u5e02\u5b98\u54e1\u9031\u4e00\u8aaa\uff0c\u672c\u6708\u521d\u6578\u53ea\u6389\u9032\u6d29\u6d2a\u9053\u4e2d\u7684\u88ab\u54e1\u8b66\u6551\u51fa\u7684\u5c0f\u9d28\u76ee\u524d\u548c\u5b83\u5011\u7684\u6bcd\u89aa\u5718\u805a\u3002 Walnut\u00a0Creek\u8b66\u65b96\u67081\u65e5\u767c\u4f48\u4e00\u5f35\u7167\u7247\u3002\u7167\u7247\u4e0a\uff0c\u8b66\u54e1\u5011\u6b63\u5728\u52aa\u529b\u6436\u6551\u9019\u4e9b\u5c0f\u9d28\u5b50\u3002\u4ed6\u5011\u6536\u5230\u4e86\u6578\u500b\u5c45\u6c11\u6253\u4f86\u7684\u96fb\u8a71\uff0c\u5927\u7d04\u56db\u540d\u8b66\u54e1\u9f4a\u5fc3\u5354\u529b\u6551\u51fa\u4e86\u9019\u4e9b\u5c0f\u9d28\u5b50\u3002 Walnut\u00a0Creek\u9031\u4e00\u66f4\u65b0Facebook\u7db2\u9801\uff0c\u767c\u4f48\u4e86\u66f4\u591a\u6551\u63f4\u7167\u7247\uff0c\u4e26\u8aaa\uff0c\u300c\u5f88\u9ad8\u8208\u5831\u544a\u5927\u5bb6\u9019\u4e9b\u5c0f\u9d28\u5b50\u8207\u5abd\u5abd\u5718\u805a\u4e86!\u300d","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2016\/06\/duck-saving.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2016\/06\/duck-saving.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2016\/06\/duck-saving.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":234403,"url":"https:\/\/newsforchinese.com\/v3\/2023\/01\/29\/%e5%8a%a0%e5%b7%9e%e6%b8%af%e5%8f%a3%e8%b7%8c%e8%90%bd%e7%a5%9e%e5%a3%87\/","url_meta":{"origin":86083,"position":1},"title":"\u52a0\u5dde\u6e2f\u53e3\u8dcc\u843d\u795e\u58c7","author":"Raymond","date":"January 29, 2023","format":false,"excerpt":"\u9019\u5834\u761f\u75ab\u6539\u8b8a\u7684\u6b77\u53f2\u9084\u771f\u591a\uff0c154\u5e74\u7684\u5927\u5b78\u88ab\u8feb\u95dc\u9589\uff0c\u9023\u7e8c22\u5e74\u7f8e\u570b\u541e\u5410\u91cf\u6700\u5927\u7684\u8ca8\u6ac3\u6e2f\u53e3\u4e5f\u8981\u8dcc\u843d\u795e\u58c7\u3002 \u6d1b\u6749\u78ef\u6e2f\u904e\u53bb\u6bcf\u5e74\u5e73\u5747\u9032\u53e3\u4e00\u5343\u842c\u53ea\u8ca8\u6ac3\u5230\u7f8e\u570b\uff0c\u662f\u5317\u7f8e\u6700\u7e41\u5fd9\u7684\u8ca8\u6ac3\u6e2f\uff0c\u540c\u6642\u4e5f\u70ba\u52a0\u5dde\u6bcf\u5e74\u5e36\u4f86\u7d04\u4e94\u5341\u5104\u7684\u6536\u5165\uff0c\u4f46\u5f9e\u53bb\u5e74\u4e5d\u6708\u958b\u59cb\uff0c\u9019\u6842\u51a0\u88ab\u6771\u5cb8\u7684\u7d10\u7d04\u8207\u7d10\u6fa4\u897f\u6e2f(NY\/NJ)\u7d66\u6436\u53bb\u4e86\uff0c\u96d6\u7136\u4e5f\u8a72\u8b93\u6771\u5cb8\u8207\u58a8\u897f\u54e5\u7063\u7684\u6e2f\u53e3\u7e41\u69ae\u4e00\u4e0b\uff0c\u4f46\u82e5\u4e0d\u53cd\u7701\uff0c\u6240\u6709\u632b\u6557\u90fd\u602a\u5230\u761f\u75ab\u982d\u4e0a\uff0c\u5c07\u6539\u8b8a\u7684\u6b77\u53f2\u9084\u6703\u66f4\u591a\u3002 \u662f\u7684\uff0c\u4e0d\u80fd\u4ec0\u9ebc\u4e8b\u90fd\u602a\u5230\u761f\u75ab\u982d\u4e0a\uff0c\u96d6\u7136\u53ef\u80fd\u662f\u5b83\u8d77\u7684\u982d\u3002CNN\u5831\u5c0e\u5206\u6790\uff0c\u6d1b\u6749\u78ef\u6e2f\u5931\u53bb\u8239\u904b\u5546\u7684\u8208\u8da3\uff0c\u4e3b\u56e0\u662f\u4ed6\u5011\u770b\u898b\u4e86\u52a0\u5dde\u6e2f\u53e3\u7684\u7f77\u5de5\uff0c\u9020\u6210\u904b\u8f38\u904e\u7a0b\u7684\u4e0d\u78ba\u5b9a\u6027\uff0c\u800c\u9019\u9ede\u6bd4\u7e5e\u9060\u8def\uff0c\u591a\u82b1\u9ede\u6642\u9593\u8207\u8cbb\u7528\u90fd\u9084\u4f86\u5f97\u56b4\u91cd\u3002\u5168\u570b\u96f6\u552e\u696d\u806f\u76df(NRF)\u7684\u4f9b\u61c9\u934a\u548c\u6d77\u95dc\u653f\u7b56\u526f\u7e3dJonathan Gold\u5c0dCNN\u89e3\u91cb\u8aaa\uff1a\u300c\u4e0d\u78ba\u5b9a\u6027\u662f\u96f6\u552e\u5546\u548c\u8239\u904b\u696d\u8005\u6700\u5bb3\u6015\u7684\uff0c\u4ed6\u5011\u4e0d\u60f3\u88ab\u56f0\u5728\u56e0\u52de\u5de5\u60c5\u52e2\u6216\u5176\u5b83\u4ec0\u9ebc\uff0c\u53ef\u80fd\u6703\u5f15\u8d77\u4e00\u5834\u6df7\u4e82\u7684\u9019\u7a2e\u60c5\u6cc1\u4e0b\u3002\u300d \u9019\u7a2e\u56f0\u5883\u5c31\u767c\u751f\u5728\u53bb\u5e74\u4e00\u6708\uff0c\u76f8\u4fe1\u5168\u4e16\u754c\u7684\u4eba\u90fd\u88ab\u897f\u5cb8\u8ca8\u6ac3\u8f2a\u585e\u5728\u6e2f\u53e3\u5916\u7684\u58ef\u89c0\u666f\u8c61\u7d66\u5687\u5230\uff0c\u7c21\u76f4\u6bd4\u8afe\u66fc\u7b2c\u767b\u9678\u9084\u58ef\u89c0\uff0c\u6700\u9ad8\u7d00\u9304\u6709109\u8258\u8239\u5728\u6e2f\u5916\u6392\u968a\u3002\u5728\u6d1b\u6749\u78ef\u6e2f\u8207\u9577\u5824\u6e2f\u5916\u7b49\u500b\u6578\u661f\u671f\u662f\u5bb6\u5e38\u4fbf\u98ef\uff0c\u800c\u9019\u5f71\u97ff\u5230\u4e862021\u7684\u5e74\u7d42\u5047\u65e5\u8cfc\u7269\u5b63\u7684\u8ca8\u904b\uff0c\u5c0e\u81f4\u4e4b\u5f8c\u6578\u6708\u7f8e\u570b\u96f6\u552e\u5546\u7684\u8ca8\u67b6\u5e38\u5e38\u7a7a\u7a7a\u5982\u4e5f\uff0c\u5546\u54c1\u50f9\u683c\u81ea\u7136\u6500\u5347\u3002\u5176\u4e2d\u65b0\u8eca\u98c6\u6f32\u6700\u80fd\u4ee3\u8868\u8ca8\u6ac3\u8f2a\u585e\u6e2f\u7684\u56b4\u91cd\u6027\uff0c\u56e0\u70ba\u4f86\u81ea\u4e9e\u6d32\u7684\u4f9b\u61c9\u93c8\u662f\u65b0\u8eca\u7684\u6838\u5fc3\uff0c\u96d6\u7136\u4f9b\u61c9\u93c8\u4e5f\u56e0\u75ab\u60c5\u5f71\u97ff\u5728\u7522\u5730\u5c31\u51fa\u554f\u984c\u4e86\u3002\u53e6\u5916\uff0c\u8ca8\u904b\u4e0d\u8db3\u4e5f\u4e0d\u80fd\u5168\u602a\u78bc\u982d\uff0c\u7576\u6642\u706b\u8eca\u8ca8\u904b\u8207\u5361\u8eca\u904b\u8f38\u90fd\u51fa\u554f\u984c\uff0c\u50cf\u8457\u540d\u7684\u52a0\u5dde\u6e2f\u53e3\u8ca8\u6ac3\u8eca\u53f8\u6a5f\u7f77\u5de5\uff0c\u90fd\u662f\u5728\u58d3\u57ae\u99f1\u99dd\u7684\u91cd\u64d4\u3002\u524d\u5e74\u7684\u5669\u5922\u96d6\u7136\u9192\u4e86\u4e00\u6703\u5152\uff0c\u4f46\u7d42\u7a76\u6c92\u6709\u812b\u96e2\u3002 \u585e\u6e2f\u7684\u6838\u5fc3\u662f\u570b\u969b\u9577\u5cb8\u548c\u5009\u5eab\u5de5\u6703\uff08ILWU\uff09\u548c\u592a\u5e73\u6d0b\u6d77\u4e8b\u5354\u6703\uff08PMA\uff09\u4e4b\u9593\u7684\u52de\u52d5\u5408\u7d04\u4e00\u76f4\u6c92\u89e3\u6c7a\uff0c\u81ea\u53bb\u5e747\u67081\u65e5\u4ee5\u5f8c\uff0cILWU\u4ee3\u8868\u7684\u5305\u62ec\u6d1b\u6749\u78ef\u548c\u9577\u7058\u5728\u5167\u7684\u897f\u5cb8\u6e2f\u53e3\u5927\u7d04\u5169\u842c\u540d\u78bc\u982d\u5de5\u4eba\uff0c\u4fbf\u4e00\u76f4\u5728\u6c92\u6709\u5408\u7d04\u7684\u60c5\u6cc1\u4e0b\u5de5\u4f5c\uff0c\u9019\u53c8\u8b93\u96f6\u552e\u5546\u7dca\u5f35\u4e86\uff0c\u4e0d\u65b7\u5730\u8ac7\u5224\u53c8\u4e0d\u65b7\u5730\u7834\u88c2\u518d\u53c8\u4e0d\u65b7\u5730\u7f77\u5de5\uff0c\u9019\u5df2\u662f\u6a19\u6e96\u7684\u7f8e\u570b\u52de\u8cc7\u96d9\u65b9\u6232\u78bc\uff0c\u96f6\u552e\u5546\u5687\u6b7b\u4e86\uff0c\u5c24\u5176\u7f8e\u570b\u9435\u8def\u8ca8\u904b\u7f77\u5de5\u4e8b\u4ef6\uff0c\u5e7e\u4e4e\u8b93\u6574\u500b\u7f8e\u570b\u7d93\u6fdf\u505c\u64fa\uff0c\u73fe\u5728\u897f\u5cb8\u78bc\u982d\u7684\u4e0d\u5b9a\u6642\u70b8\u5f48\u53c8\u5c1a\u672a\u62c6\uff0c\u8c48\u80fd\u518d\u5192\u8ca8\u67b6\u7a7a\u7a7a\u5982\u4e5f\u7684\u98a8\u96aa\u5462\uff1f \u65bc\u662f\u518d\u628a\u8ca8\u6ac3\u8f2a\u8f49\u5230\u58a8\u897f\u54e5\u7063\u8207\u6771\u5cb8\u7684\u78bc\u982d\uff0c\u591a\u82b1\u7684\u904b\u8cbb\u7576\u4f5c\u8cb7\u4fdd\u96aa\u5427\uff01Gold\u8aaa\uff1a\u300c\u6211\u5011\u5df2\u7d93\u8eb2\u904e\u4e86\u4e00\u5834\u9435\u8def\u7f77\u5de5\uff0c\u96f6\u552e\u4f9b\u61c9\u93c8\u61c9\u8a72\u80fd\u5920\u8f15\u9b06\u61c9\u4ed8\u5047\u671f\u5b63\u7684\u5269\u9918\u5e7e\u500b\u79ae\u62dc\u5427\uff01\u300d\u6240\u4ee5\u7d55\u4e0d\u5141\u8a31\u7269\u6d41\u65b9\u9762\u518d\u6709\u51fa\u554f\u984c\u7684\u98a8\u96aa\uff0c\u5118\u7ba1\u7576\u4e8b\u7684\u52de\u8cc7\u96d9\u65b9\u90fd\u91cd\u7533\u4e0d\u6703\u91cd\u6f14\u7576\u5e74\u585e\u6e2f\uff0c\u4e00\u5b9a\u6703\u4fdd\u6301\u897f\u5cb8\u6e2f\u53e3\u7684\u7af6\u722d\u529b\u3002 \u96f6\u552e\u5546\u7684\u6050\u61fc\u662f\u58d3\u8de8\u6d1b\u6749\u78ef\u6e2f\u7684\u6700\u5f8c\u4e00\u6839\u7a3b\u8349\uff0c\u81ea\u53bb\u5e74\u516b\u6708\u4ee5\u5f8c\uff0c\u897f\u5cb8\u7684\u5169\u5927\u6e2f\u53e3\u6d1b\u6749\u78ef\u8207\u9577\u7058\uff0c\u9032\u53e3\u8ca8\u904b\u91cf\u5927\u5e45\u4e0b\u964d\u3002\u8207\u524d\u5e74\u540c\u671f\u76f8\u6bd4\uff0c\u6d1b\u6749\u78ef\u6e2f\u8ca8\u904b\u91cf\u57289\u81f311\u7684\u9023\u7e8c\u4e09\u500b\u6708\u4e2d\u4e0b\u964d\u4e8625%\uff0c\u6bd4\u4e94\u5e74\u5e73\u5747\u6578\u91cf\u4e5f\u5c11\u4e8617.3%\u3002\u8ca8\u7269\u90fd\u88ab\u8f49\u904b\u5230\u58a8\u897f\u54e5\u7063\u6cbf\u5cb8\u6e2f\u53e3\uff0c\u4f8b\u5982Savannah\u8207\u7d10\u5967\u826f\uff0c\u4ee5\u53ca\u6771\u5cb8\u7684NY\/NJ\u6e2f\u3002\u8dcc\u843d\u7684\u4ea4\u53c9\u9ede\u51fa\u73fe\u5728\u516b\u6708\uff0c\u7576\u6642\u7684NY\/NJ\u8655\u7406\u4e86843K TEU\u9032\u51fa\u53e3\u8ca8\u6ac3\u91cf\uff0c\u6d1b\u6749\u78ef\u662f805K\uff0c\u6bd4\u9577\u7058\u9084\u5c11\u4e862000\u53ea\u3002\u4e4b\u5f8cNY\/NJ\u4fbf\u4e00\u8def\u9818\u5148\uff0c\u800c\u4e14\u5dee\u8ddd\u52a0\u5927\u4e2d\uff0c\u56e0\u70ba\u52a0\u5dde\u9019\u5169\u5927\u6e2f\u53e3\u8dcc\u52e2\u66f4\u5147\uff0c\u5e7e\u4e4e\u5feb\u8981\u88abSavannah\u4e5f\u8d95\u4e0a\u4e86\u3002 NY\/NJ\u6e2f\u52d9\u5c40\u65bc\u5341\u4e8c\u6708\u5f88\u9ad8\u8abf\u5730\u5ba3\u5e03\u8aaa\uff0c\u5df2\u7d93\u9023\u7e8c\u56db\u500b\u6708\u5168\u7f8e\u7b2c\u4e00\u4e86\uff0c\u57f7\u884c\u8463\u4e8bRick Cotton\u8aaa\uff1a\u300c\u6211\u5011\u9019\u6e2f\u53e3\u975e\u5e38\u52aa\u529b\u5728\u5de5\u4f5c\uff0c\u597d\u8b93\u5b83\u6210\u70ba\u6d77\u904b\u696d\u8005\u773c\u4e2d\u6700\u5177\u9b45\u529b\u7684\u6e2f\u53e3\u3002\u300d \u9019\u8a71\u807d\u5728\u6d1b\u6749\u78ef\u8033\u88e1\u9435\u5b9a\u4e0d\u662f\u6ecb\u5473\uff0c\u96e3\u9053\u6211\u5011\u6c92\u5728\u52aa\u529b\u5de5\u4f5c\u55ce\uff1f\u6e2f\u52d9\u5c40\u57f7\u884c\u8463\u4e8bGene Seroka\u8aaa\uff1a\u300c\u5728\u672a\u4f86\u7684\u5e7e\u500b\u6708\u4e2d\uff0c\u6211\u5011\u5c07\u4e0d\u5f97\u4e0d\u66f4\u52a0\u52aa\u529b\uff0c\u66f4\u8070\u660e\u5730\u628a\u9019\u4e9b\u8ca8\u7269\u8d0f\u56de\u4f86\u3002\u6bcf\u8258\u8239\u3001\u6bcf\u5217\u706b\u8eca\u3001\u6bcf\u8f1b\u5361\u8eca\u90fd\u9700\u8981\u4ee5\u6211\u5011\u5ba2\u6236\u6240\u671f\u5f85\u8207\u61c9\u5f97\u7684\u9802\u7d1a\u670d\u52d9\u4f86\u8655\u7406\u3002\u300d\u4e0d\u904e\u4ed6\u4e5f\u63d0\u5230\uff0c\u9664\u4e86\u56e0\u70ba\u52de\u8cc7\u8ac7\u5224\u800c\u5f9e\u897f\u5cb8\u6e2f\u53e3\u8f49\u79fb\u51fa\u53bb\u5916\uff0c\u7f8e\u570b\u4e0d\u518d\u662f\u975e\u5e38\u4f9d\u8cf4\u9032\u53e3\u7684\u570b\u5bb6\u4e5f\u662f\u5176\u4e00\u3002 \u602a\u6771\u602a\u5357\u9084\u4e0d\u5982\u602a\u5c0d\u624b\u9032\u6b65\u592a\u5feb\uff0c\u8b93\u81ea\u5df1\u5931\u53bb\u7af6\u722d\u529b\u3002Cotton\u8aaaNY\/NJ\u6e2f\u76ee\u524d\u5b8c\u5168\u6709\u80fd\u529b\u8655\u7406\u984d\u5916\u589e\u52a0\u7684\u8ca8\u6ac3\u91cf\uff0c\u4e5f\u6709\u4fe1\u5fc3\u51a0\u8ecd\u5bf6\u5ea7\u53ef\u4ee5\u6301\u7e8c\u5750\u4e0b\u53bb\uff0c\u4e26\u4e0d\u6253\u7b97\u653e\u68c4\u4efb\u4f55\u8dd1\u5230\u5bb6\u9580\u53e3\u7684\u751f\u610f\uff0c\u56e0\u70ba\u4ed6\u5011\u904e\u53bb\u7684\u4e94\u5e74\u6e2f\u53e3\u5efa\u8a2d\u6295\u8cc7\uff0c\u5df2\u7d93\u8a72\u4e0a\u6230\u5834\u4e86\u3002\u6b64\u5916\uff0cCotton\u4e5f\u8a8d\u70ba\u8239\u904b\u696d\u8005\u63db\u6e2f\u53e3\u662f\u70ba\u4e86\u81ea\u8eab\u4fdd\u969c\uff0c\u4ed6\u8aaa\uff1a\u300c\u4ed6\u5011\u624d\u4e0d\u8981\u628a\u6240\u6709\u96de\u86cb\u90fd\u653e\u5728\u4e00\u500b\u7c43\u5b50\u88e1\uff0c\u6240\u4ee5\u6211\u5011\u770b\u5230\u5176\u5b83\u6e2f\u53e3\u6240\u767c\u751f\u7684\u4e0b\u964d\uff0c\u4e5f\u6b63\u662fNY\/NJ\u6e2f\u6240\u767c\u751f\u7684\u66b4\u589e\u3002\u300d\u52a0\u5dde\u7684\u6e2f\u53e3\u600e\u9ebc\u7a81\u7136\u4e4b\u9593\u8b8a\u6210\u4e86\u8b93\u96de\u86cb\u5f88\u6c92\u6709\u5b89\u5168\u611f\u7684\u90a3\u500b\u7c43\u5b50\u5462\uff1f\u6216\u8a31\u9019\u624d\u662f\u5dde\u6c11\u5011\u8207\u5dde\u5b98\u54e1\u5011\uff0c\u5c24\u5176\u7acb\u6cd5\u4eba\u54e1\u8a72\u60f3\u60f3\u7684\u6838\u5fc3\u554f\u984c\uff0c\u6e2f\u52d9\u5c40\u672a\u5fc5\u80fd\u89e3\u6c7a\u3002 \u8a18\u8005 Pegasus J. Juan","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/01\/%E5%8A%A0%E5%B7%9E%E6%B8%AF%E5%8F%A3%E8%B7%8C%E8%90%BD%E7%A5%9E%E5%A3%87.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/01\/%E5%8A%A0%E5%B7%9E%E6%B8%AF%E5%8F%A3%E8%B7%8C%E8%90%BD%E7%A5%9E%E5%A3%87.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/01\/%E5%8A%A0%E5%B7%9E%E6%B8%AF%E5%8F%A3%E8%B7%8C%E8%90%BD%E7%A5%9E%E5%A3%87.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":92519,"url":"https:\/\/newsforchinese.com\/v3\/2014\/11\/22\/%e6%84%9f%e6%81%a9%e7%af%80%e5%81%87%e6%9c%9f-%e6%b4%9b%e6%9d%89%e7%a3%af%e6%a9%9f%e5%a0%b4%e5%bf%99%e7%bf%bb\/","url_meta":{"origin":86083,"position":2},"title":"\u611f\u6069\u7bc0\u5047\u671f \u6d1b\u6749\u78ef\u6a5f\u5834\u5fd9\u7ffb","author":"Raymond","date":"November 22, 2014","format":false,"excerpt":"\u6253\u7b97\u611f\u6069\u7bc0\u5047\u671f\u5230\u6d1b\u6749\u78ef\u7684\u65c5\u5ba2\u8981\u6ce8\u610f\uff0c\u4f30\u8a08\u611f\u6069\u7bc0\u5047\u671f\u671f\u9593\uff0c\u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\u53ef\u80fd\u6703\u6709\u8fd1\u5169\u767e\u842c\u4eba\u6b21\u7684\u65c5\u5ba2\u9032\u51fa\uff0c\u662f\u5168\u7f8e\u5728\u611f\u6069\u7bc0\u5047\u671f\u4e2d\u6700\u5fd9\u7684\u6a5f\u5834\u3002 \u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\uff08LAX\uff09\u516c\u95dc\u90e8\u9580\u6307\u51fa\uff0c\u5f9e\u4eca\u5929\u8d77\u523012\u67081\u65e5\uff0c\u9577\u905411\u5929\u7684\u611f\u6069\u7bc0\u5047\u671f\uff0c\u9810\u8a08\u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\u5c07\u6e67\u5165\u8fd1200\u842c\u4eba\u6b21\u7684\u65c5\u5ba2\uff0c\u6bd4\u53bb\u5e74\u589e\u52a04.8%\uff0c\u53bb\u5e74\u611f\u6069\u7bc0\u5047\u671f\u7d04\u6709182\u842c\u4eba\u6b21\u7684\u65c5\u5ba2\u3002 \u516c\u95dc\u90e8\u4e5f\u6307\u51fa\uff0c\u5728\u901911\u5929\u7684\u5047\u671f\u4e2d\uff0c\u6bcf\u500b\u822a\u7ad9\u90fd\u6703\u5f88\u5fd9\u788c\uff0c\u7f8e\u570b\u570b\u5167\u7dda\u73ed\u6a5f\u8f09\u5ba2\u7387\u53ef\u671b\u9054\u52309\u6210\uff0c\u5c24\u5176\u662f\u98db\u5f80\u820a\u91d1\u5c71\u3001\u62c9\u65af\u7dad\u52a0\u65af\u3001\u829d\u52a0\u54e5\u3001\u7d10\u7d04\u8207\u6ce2\u58eb\u9813\u7b49\u5927\u57ce\u5e02\u7684\u73ed\u6a5f\uff0c\u5e7e\u4e4e\u73ed\u73ed\u5ba2\u6eff\uff0c\u547c\u7c72\u65c5\u5ba2\u5c46\u6642\u8981\u6ce8\u610f\u81ea\u5df1\u7684\u6642\u9593\u3002 \u65c5\u904a\u696d\u8005\u8868\u793a\uff0c\u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\u589e\u52a0\u4e86\u4e0d\u5c11\u65b0\u822a\u7dda\uff0c\u63d0\u4f9b\u65c5\u5ba2\u7684\u9078\u64c7\u66f4\u591a\uff0c\u518d\u52a0\u4e0a\u8a31\u591a\u822a\u7a7a\u516c\u53f8\u90fd\u6539\u4ee5\u5927\u578b\u98db\u6a5f\u8d77\u964d\uff0c\u4f7f\u5f97\u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\u7684\u51fa\u5165\u5883\u4eba\u6b21\u4e0d\u65b7\u589e\u52a0\u3002 30\u65e5\u820712\u67081\u65e5\u5c07\u662f\u6700\u7e41\u5fd9\u7684\u5169\u5929\uff0c\u9019\u5169\u5929\u9810\u8a08\u5c07\u6709\u8d85\u904e20\u842c\u4eba\u6b21\u7684\u65c5\u5ba2\u51fa\u5165\u3002 \u65c5\u904a\u7db2\u7ad9Orbitz\u4e5f\u9810\u6e2c\uff0c\u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\u5c07\u662f\u611f\u6069\u7bc0\u5047\u671f\u4e2d\uff0c\u5168\u7f8e\u6700\u5fd9\u788c\u7684\u6a5f\u5834\u3002 \u4f86\u6e90\uff1a\u4e2d\u592e\u793e","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/11\/LAX.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/11\/LAX.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/11\/LAX.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":201435,"url":"https:\/\/newsforchinese.com\/v3\/2021\/05\/19\/%e8%81%96%e7%b8%a3%e5%92%8csanta-cruz%e7%b8%a3%e9%80%b2%e5%85%a5%e9%bb%83%e8%89%b2%e5%b1%a4%e7%b4%9a\/","url_meta":{"origin":86083,"position":3},"title":"\u8056\u7e23\u548cSanta Cruz\u7e23\u9032\u5165\u9ec3\u8272\u5c64\u7d1a","author":"Yingying","date":"May 19, 2021","format":false,"excerpt":"\u9031\u4e8c\uff0cSanta Cruz\u548cSanta Clara\u5169\u7e23\u9032\u5165\u5dde\u75ab\u60c5\u91cd\u65b0\u958b\u653e\u7cfb\u7d71\u9ec3\u8272\u5c64\u7d1a\uff0c\u6210\u70ba\u5927\u7063\u5340\u7b2c\u4e09\u548c\u7b2c\u56db\u500b\u9032\u5165\u9019\u500b\u9650\u5236\u6027\u6700\u4f4e\u5c64\u7d1a\u7684\u7e23\u3002\u8abf\u6574\u9031\u4e09\u4e0a\u534812:01\u751f\u6548\uff0c\u9019\u5169\u500b\u7e23\u56e0\u6b64\u5c07\u53ef\u4ee5\u64f4\u5927\u9910\u5ef3\u548c\u5065\u8eab\u623f\u7b49\u5546\u5bb6\u7684\u5ba4\u5167\u5bb9\u91cf\uff0c\u4ee5\u53ca\u4e3b\u984c\u516c\u5712\u548c\u5927\u578b\u6d3b\u52d5\u5834\u6240\u7b49\u5546\u5bb6\u7684\u5ba4\u5916\u5bb9\u91cf\u3002 \u9019\u5169\u500b\u7e23\u7684\u9152\u5427\u4e5f\u5c07\u53ef\u4ee5\u91cd\u555f\u5ba4\u5167\u958b\u653e\uff0c\u5bb9\u91cf\u70ba25%\u6216100\u4eba\uff08\u4ee5\u4eba\u6578\u8f03\u5c11\u8005\u70ba\u51c6\uff09\uff1b\u4e26\u4e14\u4e0d\u5fc5\u518d\u914d\u9910\u4f9b\u9152\u3002 Santa Clara\u7e23\u5065\u5eb7\u5b98Sara Cody\u535a\u58eb\u7a31\uff0c\u5c64\u7d1a\u8b8a\u5316\u5c0d\u7e23\u662f\u4e00\u500b\u300c\u5de8\u5927\u91cc\u7a0b\u7891\u300d\u3002\u5373\u4f7f\u5728\u53bb\u5e74\u79cb\u5929\uff0c\u5728\u5dde\u75c5\u4f8b\u51ac\u5b63\u6fc0\u589e\u524d\uff0c\u7e23\u4e5f\u672a\u66fe\u9054\u5230\u9ec3\u8272\u5c64\u7d1a\u3002 \u518d\u904e\u4e0d\u5230\u4e00\u500b\u6708\u6642\u9593\uff0c\u52a0\u5dde\u8a08\u756b\u53d6\u6d88\u9019\u500b\u6b63\u5f0f\u540d\u7a31\u70ba\u300cBlueprint for a Safer Economy\u300d\u7684\u5c64\u7d1a\u5236\u5ea6\uff0c\u57286\u670815\u65e5\u5141\u8a31\u5404\u7e23\u4ee5\u5b8c\u5168\u5bb9\u91cf\u91cd\u65b0\u958b\u653e\u5927\u591a\u6578\u5546\u5bb6\u3002 \u622a\u81f3\u9031\u4e8c\uff0c\u5dde58\u500b\u7e23\u4e2d\u670913\u500b\u7e23\u5c6c\u65bc\u9ec3\u8272\u5c64\u7d1a\u3002\u96d6\u7136\u7e23\u6578\u91cf\u4e0d\u591a\uff0c\u4f46\u5305\u62ecSan Francisco\u3001San Mateo\u548c\u6d1b\u6749\u78ef\u5728\u5167\u7684\u9019\u4e9b\u7e23\u5360\u5dde\u4eba\u53e3\u768443.8%\u3002 \u6b64\u5916\uff0c\u5168\u52a0\u5dde\u6c92\u6709\u4e00\u500b\u7e23\u8655\u65bc\u6700\u56b4\u683c\u7684\u7d2b\u8272\u5c64\u7d1a\u3002\u5927\u7063\u5340\u53ea\u6709Solano\u7e23\u8655\u65bc\u7d05\u8272\u5c64\u7d1a\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2020\/07\/reopen.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2020\/07\/reopen.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2020\/07\/reopen.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":171785,"url":"https:\/\/newsforchinese.com\/v3\/2019\/06\/12\/%e3%80%8ccalifas%e3%80%8d%e8%bb%8a%e7%89%8c%e9%9c%b2%e9%a4%a1-%e8%b2%a0%e7%bd%aa%e5%8d%a1%e8%bb%8a%e5%8f%b8%e6%a9%9f%e8%a2%ab%e6%8a%93\/","url_meta":{"origin":86083,"position":4},"title":"\u300cCALIFAS\u300d\u8eca\u724c\u9732\u9921\u00a0\u00a0\u8ca0\u7f6a\u5361\u8eca\u53f8\u6a5f\u88ab\u6293","author":"Yingying","date":"June 12, 2019","format":false,"excerpt":"\u4e00\u584a\u507d\u9020\u7684\u8001\u5f0f\u52a0\u5dde\u8eca\u724c\u5c0e\u81f4\u4e00\u540d\u5927\u5361\u8eca\u53f8\u6a5f\u88ab\u902e\u6355\u3002\u9019\u540d\u5927\u5361\u8eca\u53f8\u6a5f\u88ab\u6355\u6d89\u5acc\u7684\u7f6a\u540d\u5305\u62ec\u9152\u5f8c\u99d5\u8eca\u3001\u6301\u6709\u7532\u57fa\u82ef\u4e19\u80fa\u4ee5\u53caVentura\u7e23\u5176\u4ed6\u72af\u7f6a\u884c\u70ba\u3002 \u4e00\u540d\u6469\u6258\u8eca\u8b66\u54e1\u6ce8\u610f\u5230\u9019\u540d\u5927\u5361\u8eca\u53f8\u6a5f\u7684\u8eca\u724c\u4e0d\u592a\u6b63\u5e38\uff0c\u65bc\u662f\u5728Moorpark\u8b93\u4ed6\u9760\u908a\u505c\u8eca\u3002Moorpark\u5728\u6d1b\u6749\u78ef\u897f\u5317\u7d0450\u82f1\u91cc\u8655\u3002\u9019\u584a\u8eca\u724c\u6709\u4e00\u500b1960\u5e74\u4ee3\u53e4\u8463\u8eca\u724c\u7684\u9ec3\u8272\u5b57\u9ad4\u548c\u9ed1\u8272\u80cc\u666f\uff0c\u4f46\u76f8\u4f3c\u4e4b\u8655\u50c5\u6b64\u800c\u5df2\u3002 \u8eca\u724c\u8b58\u5225\u865f\u4e0a\u65b9\u7684\u55ae\u5b57\u4e0d\u662f\u300cCALIFORNIA\u300d\uff0c\u800c\u662f\u300cCALIFAS\u300d\u3002 Ventura\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5728\u9031\u4e09\u8072\u660e\u4e2d\u8aaa\uff0c\u9019\u540d\u5927\u5361\u8eca\u53f8\u6a5f\u672c\u5df2\u6709\u902e\u6355\u4ee4\u5728\u8eab\u3002\u95dc\u65bc\u902e\u6355\u4ee4\u7684\u7d30\u7bc0\u76ee\u524d\u9084\u4e0d\u6e05\u695a\u3002 \u8b66\u65b9\u8aaa\uff0c\u7531\u65bc\u99d5\u99db\u4e0d\u5b89\u5168\uff0c\u5927\u5361\u8eca\u88ab\u62d6\u96e2\u4e86\u73fe\u5834\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2019\/06\/fake-plate.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2019\/06\/fake-plate.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2019\/06\/fake-plate.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":166479,"url":"https:\/\/newsforchinese.com\/v3\/2019\/01\/20\/%e6%b4%9b%e6%9d%89%e7%a3%af%e9%81%8a%e5%ae%a2%e4%ba%ba%e6%95%b8%e7%aa%81%e7%a0%b45000%e8%90%ac%e5%a4%a7%e9%97%9c\/","url_meta":{"origin":86083,"position":5},"title":"\u6d1b\u6749\u78ef\u904a\u5ba2\u4eba\u6578\u7a81\u78345000\u842c\u5927\u95dc","author":"Yingying","date":"January 20, 2019","format":false,"excerpt":"\u6d1b\u6749\u78efTourism & Convention Board(\u65c5\u904a\u8207\u6703\u8b70\u59d4\u54e1\u6703)\u8fd1\u65e5\u5ba3\u4f48\uff0c2018\u5e74\u6d1b\u6749\u78ef\u904a\u5ba2\u9996\u6b21\u8d85\u904e5000\u842c\u4eba\u6b21\u3002 \u65b0\u8a18\u9304\u6bd42017\u5e74\u7e3d\u904a\u5ba2\u6578\u9ad8\u51fa150\u842c\uff08\u589e\u95773.1%\uff09\uff0c\u9019\u4e5f\u6a19\u8a8c\u8457\u6d1b\u6749\u78ef\u65c5\u904a\u4eba\u6578\u9023\u7e8c\u7b2c\u516b\u5e74\u589e\u9577\u3002 \u300c\u6d1b\u6749\u78ef\u662f\u4e00\u500b\u5411\u6240\u6709\u4eba\u655e\u958b\u6b61\u8fce\u5927\u9580\u7684\u5730\u65b9\uff0c\u65c5\u904a\u696d\u589e\u5f37\u4e86\u6211\u5011\u7684\u591a\u6a23\u6027\uff0c\u767c\u5c55\u4e86\u6211\u5011\u7684\u7d93\u6fdf\uff0c\u4e26\u70ba\u6211\u5011\u57ce\u5e02\u7684\u5bb6\u5ead\u63d0\u4f9b\u4e86\u9ad8\u85aa\u5de5\u4f5c\uff0c\u300d\u5e02\u9577Eric Garcetti\u8aaa\u3002\u300c\u63d0\u524d\u5169\u5e74\u7a81\u78345000\u842c\u5e74\u904a\u5ba2\u4eba\u6b21\u5927\u95dc\u662f\u6211\u5011\u5c07\u6d1b\u6749\u78ef\u5e36\u5230\u4e16\u754c\u5404\u5730\u3001\u5c07\u4e16\u754c\u5e36\u5230\u6d1b\u6749\u78ef\u52aa\u529b\u7684\u6700\u65b0\u91cc\u7a0b\u7891\u3002\u300d \u96a8\u8457\u6d1b\u6749\u78ef\u904a\u5ba2\u7e3d\u6578\u8d85\u904e5000\u842c\uff0c\u6d1b\u6749\u78ef\u540c\u6642\u5275\u4e0b\u570b\u5167\u5916\u904a\u5ba2\u65b0\u7d00\u9304\uff1a\u570b\u5167\u904a\u5ba24250\u842c\u4eba\u6b21\uff08\u589e\u95773%\uff09\uff0c\u570b\u969b\u904a\u5ba2750\u842c\u4eba\u6b21\uff08\u589e\u95773.6%\uff09\u3002 \u57282017\u5e74\u7565\u6709\u4e0b\u964d\u5f8c\uff0c2018\u5e74\u58a8\u897f\u54e5\u904a\u5ba2\u7e3d\u6578\u9054\u5230\u6709\u53f2\u4ee5\u4f86\u6700\u9ad8\u6c34\u6e96\uff0c\u904a\u5ba2\u4eba\u6578\u9054\u5230180\u842c\uff0c\u589e\u95774%\u3002 \u4e2d\u570b\u904a\u5ba2\u5275\u4e0b120\u842c\u4eba\u6578\uff0c\u6d1b\u6749\u78ef\u56e0\u6b64\u6210\u70ba\u63a5\u7d0d\u4e2d\u570b\u904a\u5ba2\u7684\u7f8e\u570b\u7b2c\u4e00\u5927\u57ce\u5e02\uff08\u589e\u95776.9%\uff0c\u662f\u6240\u6709\u570b\u969b\u5e02\u5834\u4e2d\u6700\u5927\u6de8\u589e\u9577\uff09\u3002 \u5176\u4ed6\u570b\u969b\u5e02\u5834\u5230\u8a2a\u904a\u5ba2\u4eba\u6578\u57282018\u5e74\u5747\u5275\u4e0b\u6b77\u53f2\u65b0\u9ad8\uff0c\u5305\u62ec\uff1a\u52a0\u62ff\u592778\u842c\uff08\u589e\u95774.5%\uff09\uff0c\u82f1\u570b38.2\u842c\uff08\u589e\u95773%\uff09\uff0c\u65e5\u672c34.9\u842c\uff08\u589e\u95772.5%\uff09\uff0c\u65af\u582a\u7684\u7d0d\u7dad\u4e9e19\u842c\uff08\u589e\u95773.9%\uff09\u548c\u5370\u5ea613\u842c\uff08\u589e\u95775.1%\uff09\u3002 Tourism & Convention Board\u5c07\u6d1b\u6749\u78ef\u65c5\u904a\u696d\u589e\u9577\u6b78\u56e0\u65bc\u5e7e\u500b\u56e0\u7d20\uff0c\u5176\u4e2d\u5305\u62ec\u6d1b\u6749\u78ef\u570b\u969b\u6a5f\u5834\u570b\u969b\u822a\u73ed\u5ea7\u4f4d\u5bb9\u91cf\u589e\u95773.6%\u4ee5\u53ca\u65b0\u589e\u8fd12000\u9593\u9152\u5e97\u5ba2\u623f\u3002 \u53bb\u5e74\u65c5\u904a\u696d\u70ba\u4f11\u9592\u548c\u9152\u5e97\u696d\u63d0\u4f9b\u5e73\u574754.7\u842c\u500b\u5d17\u4f4d\uff0c\u4e26\u56e0\u6b64\u6210\u70ba\u5168\u5e74\u65b0\u589e\u5d17\u4f4d\u6700\u591a\u4e00\u5e74\uff1a\u65b0\u589e22996\u500b\u5d17\u4f4d\uff0c\u589e\u5e454.4%\u3002 \u5168\u7e23\u9152\u5e97\u5ba2\u623f\u92b7\u552e\u5275\u7d00\u9304\u5730\u9054\u52303010\u842c\u9593\uff0c\u589e\u95772.4%\u3002Tourism & Convention Board\u4f30\u8a082018\u5e74\u904a\u5ba2\u70ba\u6d1b\u6749\u78ef\u5e02\u5e36\u4f86\u81f3\u5c112.88\u5104\u5143\u81e8\u6642\u4f54\u7528\u7a05(TOT)\uff0c\u9019\u4e5f\u5c07\u5275\u4e0b\u6b77\u53f2\u65b0\u9ad8\u3002TOT\u8cc7\u91d1\u7528\u65bc\u7576\u5730\u6d88\u9632\u3001\u54e1\u8b66\u4ee5\u53ca\u6587\u5316\u5a1b\u6a02\u670d\u52d9\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2019\/01\/los-angeles.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2019\/01\/los-angeles.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2019\/01\/los-angeles.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2014\/08\/yellow-duck.jpg","_links":{"self":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts\/86083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/comments?post=86083"}],"version-history":[{"count":0,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts\/86083\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/media\/86082"}],"wp:attachment":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/media?parent=86083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/categories?post=86083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/tags?post=86083"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/series?post=86083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}