{"id":244476,"date":"2023-08-14T07:32:10","date_gmt":"2023-08-14T14:32:10","guid":{"rendered":"https:\/\/newsforchinese.com\/v3\/?p=244476"},"modified":"2023-08-14T07:32:12","modified_gmt":"2023-08-14T14:32:12","slug":"%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be","status":"publish","type":"post","link":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/","title":{"rendered":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">\u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002<\/p>\n<div class=\"gsp_post_data\" \r\n\t            data-post_type=\"post\" \r\n\t            data-cat=\"local\" \r\n\t            data-modified=\"120\"\r\n\t            data-created=\"1691998330\"\r\n\t            data-title=\"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe\" \r\n\t            data-home=\"https:\/\/newsforchinese.com\/v3\"><\/div>","protected":false},"excerpt":{"rendered":"<p>\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002<\/p>\n","protected":false},"author":1001022,"featured_media":244477,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"audio","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"{title}\n\n{excerpt}\n\n{url}","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"_wpas_customize_per_network":false,"jetpack_post_was_ever_published":false},"categories":[7],"tags":[],"series":[],"class_list":["post-244476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Yingying\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<meta name=\"google-adsense-account\" content=\"ca-pub-9175855296033541\">\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19 - \u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19\" \/>\n\t\t<meta property=\"og:description\" content=\"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-08-14T14:32:10+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-08-14T14:32:12+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19\" \/>\n\t\t<meta name=\"twitter:description\" content=\"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#blogposting\",\"name\":\"\\u7591\\u4f3c\\u5931\\u8e64\\u5c11\\u5973Katie\\u907a\\u9ab8\\u88ab\\u767c\\u73fe - News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"headline\":\"\\u7591\\u4f3c\\u5931\\u8e64\\u5c11\\u5973Katie\\u907a\\u9ab8\\u88ab\\u767c\\u73fe\",\"author\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/yinyin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg\",\"width\":600,\"height\":400},\"datePublished\":\"2023-08-14T07:32:10-07:00\",\"dateModified\":\"2023-08-14T07:32:12-07:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#webpage\"},\"articleSection\":\"\\u5730\\u65b9\\u65b0\\u805e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newsforchinese.com\\\/v3\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/local\\\/#listItem\",\"name\":\"\\u5730\\u65b9\\u65b0\\u805e\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/local\\\/#listItem\",\"position\":2,\"name\":\"\\u5730\\u65b9\\u65b0\\u805e\",\"item\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/local\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#listItem\",\"name\":\"\\u7591\\u4f3c\\u5931\\u8e64\\u5c11\\u5973Katie\\u907a\\u9ab8\\u88ab\\u767c\\u73fe\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#listItem\",\"position\":3,\"name\":\"\\u7591\\u4f3c\\u5931\\u8e64\\u5c11\\u5973Katie\\u907a\\u9ab8\\u88ab\\u767c\\u73fe\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/category\\\/local\\\/#listItem\",\"name\":\"\\u5730\\u65b9\\u65b0\\u805e\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#organization\",\"name\":\"News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"description\":\"\\u8001\\u4e2d\\u5730\\u65b9\\u65b0\\u805e\\u662f\\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u65b0\\u805e\\u96c6\\u5718\\uff0c\\u591a\\u5143\\u5316\\u5e73\\u53f0\\u6709\\u65b0\\u805e\\u7db2\\u3001\\u5f71\\u97f3\\u7db2\\u3001AM1450\\u5ee3\\u64ad\\u96fb\\u53f0\\u53ca\\u514d\\u8cbb\\u5168\\u5f69\\u5831\\u7d19\\u3002\\u624b\\u6a5f\\u63d0\\u4f9b\\u6700\\u65b0\\u6700\\u5feb\\u793e\\u5340\\u65b0\\u805e\\uff0c\\u670d\\u52d960\\u842c\\u83ef\\u88d4\\u8b80\\u8005\\u3002\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/yinyin\\\/#author\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/yinyin\\\/\",\"name\":\"Yingying\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0d9f81a920b32aec0890d90773a07a58625846ffef3a348907825722779d17ce?s=96&d=retro&r=g\",\"width\":96,\"height\":96,\"caption\":\"Yingying\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#webpage\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/\",\"name\":\"\\u7591\\u4f3c\\u5931\\u8e64\\u5c11\\u5973Katie\\u907a\\u9ab8\\u88ab\\u767c\\u73fe - News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"description\":\"\\u5728Saratoga\\u7e23\\u5931\\u8e64Saratoga\\u5c11\\u5973\\u7684\\u6c7d\\u8eca\\u9644\\u8fd1\\u767c\\u73fe\\u4e86\\u4eba\\u985e\\u907a\\u9ab8\\u3002 \\u5931\\u8e64\\u5c11\\u5973Katherine \\u300cKatie\\u300d Schneider\\u7684\\u5bb6\\u4eba\\u8868\\u793a\\uff0cSanta Clara\\u7e23\\u8b66\\u9577\\u8fa6\\u516c\\u5ba4\\u5411\\u5bb6\\u4eba\\u8b49\\u5be6\\uff0c\\u907a\\u9ab8\\u5c6c\\u65bc\\u9019\\u540d\\u5c11\\u5973\\u3002 Santa Clara\\u7e23\\u8b66\\u9577\\u8fa6\\u516c\\u5ba4\\u9031\\u65e5\\u5ba3\\u4f48\\u5728Castle Rock State Park\\u9644\\u8fd1\\u767c\\u73fe\\u4eba\\u907a\\u9ab8\\u3002\\u6b64\\u524d\\uff0c\\u9019\\u540d17\\u6b72\\u5c11\\u5973\\u7684\\u6c7d\\u8eca\\u5728\\u540c\\u4e00\\u5730\\u5340Skyline Boulevard\\u88ab\\u767c\\u73fe\\u3002 \\u6839\\u64da\\u4e00\\u500b\\u5c08\\u9580\\u5c0b\\u627eKatie\\u7684Facebook\\u9801\\u9762\\uff0c\\u4ee5\\u53caKatie\\u6bcd\\u89aa\\u5728Instagram\\u548cFacebook\\u4e0a\\u7684\\u500b\\u4eba\\u793e\\u4ea4\\u5a92\\u9ad4\\u5e33\\u6236\\uff0c\\u5979\\u7684\\u907a\\u9ab8\\u5728\\u4e00\\u500b\\u5cfd\\u8c37\\u4e2d\\u88ab\\u627e\\u5230\\uff0c\\u64da\\u4fe1\\u5979\\u6b7b\\u65bc\\u99d5\\u8eca\\u4e8b\\u6545\\u3002 \\u5979\\u7684\\u6bcd\\u89aa\\u8aaa\\uff0c\\u5177\\u9ad4\\u60c5\\u6cc1\\u6b63\\u5728\\u8abf\\u67e5\\u4e2d\\u3002 \\u300c\\u5f88\\u96e3\\u7528\\u8a9e\\u8a00\\u8868\\u9054\\u4eba\\u5011\\u5c0dKatie\\u7684\\u61f7\\u5ff5\\u3002Katie\\u662f\\u4e00\\u76de\\u660e\\u71c8\\uff0c\\u7d66\\u6211\\u5011\\u7684\\u65e5\\u5e38\\u751f\\u6d3b\\u5e36\\u4f86\\u60c5\\u611f\\u7684\\u6d3b\\u529b\\u3002\\u5979\\u6563\\u767c\\u51fa\\u771f\\u5be6\\u3001\\u9ad4\\u8cbc\\u3001\\u5e7d\\u9ed8\\u611f\\u548c\\u5805\\u5b9a\\u7684\\u6c7a\\u5fc3\\u3002\\u5979\\u6559\\u6703\\u6211\\u5011\\u6240\\u6709\\u4eba\\u5982\\u4f55\\u6beb\\u7121\\u4fdd\\u7559\\u5730\\u904e\\u4e0a\\u6700\\u7f8e\\u597d\\u7684\\u751f\\u6d3b\\uff0c\\u300d\\u4e00\\u4efd\\u8072\\u660e\\u5beb\\u9053\\u3002\\u300c\\u2026\\u8acb\\u548c\\u6211\\u5011\\u4e00\\u8d77\\u95dc\\u6ce8Katie\\u7d66\\u6211\\u5011\\u548c\\u5176\\u4ed6\\u4eba\\u5e36\\u4f86\\u7684\\u611b\\u548c\\u5feb\\u6a02\\u3002\\u300d \\u8b66\\u9577\\u8fa6\\u516c\\u5ba4\\u5c1a\\u672a\\u516c\\u958b\\u78ba\\u8a8d\\u907a\\u9ab8\\u662f\\u5426\\u5c6c\\u65bcKatherine\\uff0c\\u6b63\\u5728\\u7b49\\u5f85\\u7e23\\u9a57\\u5c4d\\u5b98\\u8fa6\\u516c\\u5ba4\\u7684\\u78ba\\u8a8d\\u3002\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/yinyin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/author\\\/yinyin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#mainImage\",\"width\":600,\"height\":400},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/2023\\\/08\\\/14\\\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\\\/#mainImage\"},\"datePublished\":\"2023-08-14T07:32:10-07:00\",\"dateModified\":\"2023-08-14T07:32:12-07:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#website\",\"url\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/\",\"name\":\"News for Chinese \\uff0d \\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u83ef\\u4eba\\u793e\\u5340\\u5831\\u7d19\",\"description\":\"\\u8001\\u4e2d\\u5730\\u65b9\\u65b0\\u805e\\u662f\\u820a\\u91d1\\u5c71\\u7063\\u5340No.1\\u514d\\u8cbb\\u65b0\\u805e\\u96c6\\u5718\\uff0c\\u591a\\u5143\\u5316\\u5e73\\u53f0\\u6709\\u65b0\\u805e\\u7db2\\u3001\\u5f71\\u97f3\\u7db2\\u3001AM1450\\u5ee3\\u64ad\\u96fb\\u53f0\\u53ca\\u514d\\u8cbb\\u5168\\u5f69\\u5831\\u7d19\\u3002\\u624b\\u6a5f\\u63d0\\u4f9b\\u6700\\u65b0\\u6700\\u5feb\\u793e\\u5340\\u65b0\\u805e\\uff0c\\u670d\\u52d960\\u842c\\u83ef\\u88d4\\u8b80\\u8005\\u3002\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/newsforchinese.com\\\/v3\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002","canonical_url":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;meta name=\"google-adsense-account\" content=\"ca-pub-9175855296033541\"&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#blogposting","name":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","headline":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe","author":{"@id":"https:\/\/newsforchinese.com\/v3\/author\/yinyin\/#author"},"publisher":{"@id":"https:\/\/newsforchinese.com\/v3\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg","width":600,"height":400},"datePublished":"2023-08-14T07:32:10-07:00","dateModified":"2023-08-14T07:32:12-07:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#webpage"},"isPartOf":{"@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#webpage"},"articleSection":"\u5730\u65b9\u65b0\u805e"},{"@type":"BreadcrumbList","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3#listItem","position":1,"name":"Home","item":"https:\/\/newsforchinese.com\/v3","nextItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/category\/local\/#listItem","name":"\u5730\u65b9\u65b0\u805e"}},{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/category\/local\/#listItem","position":2,"name":"\u5730\u65b9\u65b0\u805e","item":"https:\/\/newsforchinese.com\/v3\/category\/local\/","nextItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#listItem","name":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe"},"previousItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#listItem","position":3,"name":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe","previousItem":{"@type":"ListItem","@id":"https:\/\/newsforchinese.com\/v3\/category\/local\/#listItem","name":"\u5730\u65b9\u65b0\u805e"}}]},{"@type":"Organization","@id":"https:\/\/newsforchinese.com\/v3\/#organization","name":"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002","url":"https:\/\/newsforchinese.com\/v3\/"},{"@type":"Person","@id":"https:\/\/newsforchinese.com\/v3\/author\/yinyin\/#author","url":"https:\/\/newsforchinese.com\/v3\/author\/yinyin\/","name":"Yingying","image":{"@type":"ImageObject","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/0d9f81a920b32aec0890d90773a07a58625846ffef3a348907825722779d17ce?s=96&d=retro&r=g","width":96,"height":96,"caption":"Yingying"}},{"@type":"WebPage","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#webpage","url":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/","name":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/newsforchinese.com\/v3\/#website"},"breadcrumb":{"@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#breadcrumblist"},"author":{"@id":"https:\/\/newsforchinese.com\/v3\/author\/yinyin\/#author"},"creator":{"@id":"https:\/\/newsforchinese.com\/v3\/author\/yinyin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg","@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#mainImage","width":600,"height":400},"primaryImageOfPage":{"@id":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/#mainImage"},"datePublished":"2023-08-14T07:32:10-07:00","dateModified":"2023-08-14T07:32:12-07:00"},{"@type":"WebSite","@id":"https:\/\/newsforchinese.com\/v3\/#website","url":"https:\/\/newsforchinese.com\/v3\/","name":"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","description":"\u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002","inLanguage":"en-US","publisher":{"@id":"https:\/\/newsforchinese.com\/v3\/#organization"}}]},"og:locale":"en_US","og:site_name":"News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19 - \u8001\u4e2d\u5730\u65b9\u65b0\u805e\u662f\u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u65b0\u805e\u96c6\u5718\uff0c\u591a\u5143\u5316\u5e73\u53f0\u6709\u65b0\u805e\u7db2\u3001\u5f71\u97f3\u7db2\u3001AM1450\u5ee3\u64ad\u96fb\u53f0\u53ca\u514d\u8cbb\u5168\u5f69\u5831\u7d19\u3002\u624b\u6a5f\u63d0\u4f9b\u6700\u65b0\u6700\u5feb\u793e\u5340\u65b0\u805e\uff0c\u670d\u52d960\u842c\u83ef\u88d4\u8b80\u8005\u3002","og:type":"article","og:title":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","og:description":"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002","og:url":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/","og:image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg","og:image:secure_url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg","og:image:width":600,"og:image:height":400,"article:published_time":"2023-08-14T14:32:10+00:00","article:modified_time":"2023-08-14T14:32:12+00:00","twitter:card":"summary_large_image","twitter:title":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe - News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19","twitter:description":"\u5728Saratoga\u7e23\u5931\u8e64Saratoga\u5c11\u5973\u7684\u6c7d\u8eca\u9644\u8fd1\u767c\u73fe\u4e86\u4eba\u985e\u907a\u9ab8\u3002 \u5931\u8e64\u5c11\u5973Katherine \u300cKatie\u300d Schneider\u7684\u5bb6\u4eba\u8868\u793a\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5411\u5bb6\u4eba\u8b49\u5be6\uff0c\u907a\u9ab8\u5c6c\u65bc\u9019\u540d\u5c11\u5973\u3002 Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u9031\u65e5\u5ba3\u4f48\u5728Castle Rock State Park\u9644\u8fd1\u767c\u73fe\u4eba\u907a\u9ab8\u3002\u6b64\u524d\uff0c\u9019\u540d17\u6b72\u5c11\u5973\u7684\u6c7d\u8eca\u5728\u540c\u4e00\u5730\u5340Skyline Boulevard\u88ab\u767c\u73fe\u3002 \u6839\u64da\u4e00\u500b\u5c08\u9580\u5c0b\u627eKatie\u7684Facebook\u9801\u9762\uff0c\u4ee5\u53caKatie\u6bcd\u89aa\u5728Instagram\u548cFacebook\u4e0a\u7684\u500b\u4eba\u793e\u4ea4\u5a92\u9ad4\u5e33\u6236\uff0c\u5979\u7684\u907a\u9ab8\u5728\u4e00\u500b\u5cfd\u8c37\u4e2d\u88ab\u627e\u5230\uff0c\u64da\u4fe1\u5979\u6b7b\u65bc\u99d5\u8eca\u4e8b\u6545\u3002 \u5979\u7684\u6bcd\u89aa\u8aaa\uff0c\u5177\u9ad4\u60c5\u6cc1\u6b63\u5728\u8abf\u67e5\u4e2d\u3002 \u300c\u5f88\u96e3\u7528\u8a9e\u8a00\u8868\u9054\u4eba\u5011\u5c0dKatie\u7684\u61f7\u5ff5\u3002Katie\u662f\u4e00\u76de\u660e\u71c8\uff0c\u7d66\u6211\u5011\u7684\u65e5\u5e38\u751f\u6d3b\u5e36\u4f86\u60c5\u611f\u7684\u6d3b\u529b\u3002\u5979\u6563\u767c\u51fa\u771f\u5be6\u3001\u9ad4\u8cbc\u3001\u5e7d\u9ed8\u611f\u548c\u5805\u5b9a\u7684\u6c7a\u5fc3\u3002\u5979\u6559\u6703\u6211\u5011\u6240\u6709\u4eba\u5982\u4f55\u6beb\u7121\u4fdd\u7559\u5730\u904e\u4e0a\u6700\u7f8e\u597d\u7684\u751f\u6d3b\uff0c\u300d\u4e00\u4efd\u8072\u660e\u5beb\u9053\u3002\u300c\u2026\u8acb\u548c\u6211\u5011\u4e00\u8d77\u95dc\u6ce8Katie\u7d66\u6211\u5011\u548c\u5176\u4ed6\u4eba\u5e36\u4f86\u7684\u611b\u548c\u5feb\u6a02\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u5c1a\u672a\u516c\u958b\u78ba\u8a8d\u907a\u9ab8\u662f\u5426\u5c6c\u65bcKatherine\uff0c\u6b63\u5728\u7b49\u5f85\u7e23\u9a57\u5c4d\u5b98\u8fa6\u516c\u5ba4\u7684\u78ba\u8a8d\u3002","twitter:image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg"},"aioseo_meta_data":{"post_id":"244476","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-08-14 14:32:12","updated":"2025-06-11 09:23:41","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/newsforchinese.com\/v3\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/newsforchinese.com\/v3\/category\/local\/\" title=\"\u5730\u65b9\u65b0\u805e\">\u5730\u65b9\u65b0\u805e<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/newsforchinese.com\/v3"},{"label":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},{"label":"\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe","link":"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/"}],"featured_image_urls":{"medium":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-300x200.jpg","thumbnail":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-150x150.jpg","post-thumbnail-size":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-600x330.jpg","round-personnel-size":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-400x400.jpg","small-grid-size":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-400x300.jpg","portrait":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-500x400.jpg","post-widget-left-featured":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-600x350.jpg","post-board-1-2":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-450x400.jpg","post-board-2-2":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says-600x332.jpg"},"appp_media":null,"episode_featured_image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg","episode_player_image":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2022\/11\/avatars-DFF30y5My1u3eZvX-2nXMSw-original.jpg","download_link":"","player_link":"","audio_player":false,"episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"https:\/\/newsforchinese.com\/v3\/feed\/podcast\/%e8%80%81%e4%b8%ad%e5%bb%a3%e6%92%ad%e9%9b%bb%e5%8f%b0","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"o4UU3qbbsv\"><a href=\"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/\">\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/newsforchinese.com\/v3\/2023\/08\/14\/%e7%96%91%e4%bc%bc%e5%a4%b1%e8%b9%a4%e5%b0%91%e5%a5%b3katie%e9%81%ba%e9%aa%b8%e8%a2%ab%e7%99%bc%e7%8f%be\/embed\/#?secret=o4UU3qbbsv\" width=\"500\" height=\"350\" title=\"&#8220;\u7591\u4f3c\u5931\u8e64\u5c11\u5973Katie\u907a\u9ab8\u88ab\u767c\u73fe&#8221; &#8212; News for Chinese \uff0d \u820a\u91d1\u5c71\u7063\u5340No.1\u514d\u8cbb\u83ef\u4eba\u793e\u5340\u5831\u7d19\" data-secret=\"o4UU3qbbsv\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/newsforchinese.com\/v3\/wp-includes\/js\/wp-embed.min.js\n<\/script>\n"},"jetpack_publicize_connections":[],"jetpack-related-posts":[{"id":228949,"url":"https:\/\/newsforchinese.com\/v3\/2022\/11\/06\/oakley%e5%a5%b3%e5%ad%90gabe%e9%83%a8%e5%88%86%e9%81%ba%e9%aa%b8%e8%a2%ab%e6%89%be%e5%88%b0\/","url_meta":{"origin":244476,"position":0},"title":"Oakley\u5973\u5b50Gabe\u90e8\u5206\u907a\u9ab8\u88ab\u627e\u5230","author":"Yingying","date":"November 6, 2022","format":false,"excerpt":"\u64da\u8b66\u65b9\uff0c\u672c\u9031\u5728Amador\u7e23\u767c\u73fe\u7684\u4eba\u985e\u907a\u9ab8\u5c6c\u65bc\u4eca\u5e741\u6708\u5931\u8e64\u7684Oakley\u5973\u5b50Alexis Gabe\u3002 \u9031\u56db\u4e0b\u5348\uff0cPlymouth\u93ae\u4e00\u540d\u5c45\u6c11\u767c\u73fe\u4e00\u4e9b\u7591\u4f3c\u4eba\u985e\u907a\u9ab8\u7684\u6771\u897f\u3002\u9019\u4f4d\u5c45\u6c11\u901a\u77e5\u4e86Amador\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\uff0c\u8b66\u9577\u8fa6\u516c\u5ba4\u8b66\u54e1\u548c\u8abf\u67e5\u4eba\u54e1\u96a8\u5373\u524d\u5f80\u8a72\u5340\u57df\u67e5\u770b\u907a\u9ab8\u3002 \u7531\u65bc\u7576\u6642\u5929\u8272\u5df2\u665a\uff0c\u8b66\u65b9\u6c7a\u5b9a\u5148\u5c0d\u8a72\u5340\u57df\u9032\u884c\u76e3\u63a7\uff0c\u7136\u5f8c\u5728\u9031\u4e94\u65e9\u4e0a\u5c55\u958b\u66f4\u5fb9\u5e95\u8abf\u67e5\u3002 Oakley\u8b66\u5bdf\u5c40\u548cAntioch\u8b66\u5bdf\u5c40\u6210\u54e1\u9031\u4e94\u6e05\u6668\u524d\u5f80Plymouth\u5354\u52a9\u8abf\u67e5\u3002 Oakley\u8b66\u65b9\u9031\u4e94\u665a\u8868\u793a\uff0c\u5177\u9ad4\u5730\u9ede\u5728Plymouth\u7684Jackson Road\u9644\u8fd1\u3002\u8b66\u65b9\u5c0d\u767c\u73feAlexis\u907a\u9ab8\u7684\u5340\u57df\u9032\u884c\u4e86\u9032\u4e00\u6b65\u641c\u7d22\uff0c\u4f46\u672a\u627e\u5230\u5176\u4ed6\u907a\u9ab8\u3002 \u8abf\u67e5\u8b49\u5be6\u90e8\u5206\u907a\u9ab8\u5c6c\u65bc\u4eba\u985e\u3002\u4e00\u540d\u6cd5\u91ab\u7259\u91ab\u524d\u5f80Amador\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u6aa2\u67e5\u907a\u9ab8\u3002\u9019\u4f4d\u5c08\u5bb6\u5341\u5206\u80af\u5b9a\u5730\u8a8d\u70ba\u907a\u9ab8\u5c6c\u65bcGabe\u3002 \u64daOakley\u8b66\u65b9\uff0cGabe\u5bb6\u4eba\u5df2\u63a5\u5230\u901a\u77e5\u3002 Oakley\u8b66\u65b9\u8868\u793a\uff1a\u300c\u7531\u65bcAlexis\u907a\u9ab8\u7684\u6027\u8cea\u548c\u7f3a\u4e4f\u5b8c\u6574\u8eab\u9ad4\uff0c\u6211\u5011\u8a8d\u70ba\u5979\u7684\u907a\u9ab8\u5206\u6563\u5728\u4e0d\u540c\u5730\u5340\u3002\u300d \u8003\u616e\u5230Gabe\u907a\u9ab8\u72c0\u6cc1\uff0cOakley\u8b66\u65b9\u610f\u8b58\u5230\u53ef\u80fd\u6c38\u9060\u7121\u6cd5\u627e\u56de\u5168\u90e8\u7684\u5979\u3002Oakley\u5e02\u5df2\u6c7a\u5b9a\uff0c\u4e0d\u518d\u5c0d\u672a\u4f86\u53ef\u80fd\u767c\u73fe\u4efb\u4f55\u907a\u9ab8\u767c\u653e\u734e\u91d1\u3002 \u6f2b\u9577\u800c\u75db\u82e6\u7684\u641c\u7d22 24\u6b72\u7684Alexis Gabe1\u6708\u5931\u8e64\uff0c\u5728\u88ab\u78ba\u8a8d\u6b7b\u4ea1\u5f8c\uff0c\u5979\u7684\u907a\u9ad4\u4e00\u76f4\u6c92\u6709\u88ab\u627e\u5230\u30021\u670826\u65e5\uff0c\u5979\u6700\u5f8c\u4e00\u6b21\u88ab\u767c\u73fe\u662f\u5728\u5979\u7537\u670b\u53cb\u5728Antioch\u7684\u5bb6\u3002\u5e7e\u5929\u5f8c\uff0c\u5979\u7684\u8eca\u5728Oakley\u88ab\u767c\u73fe\uff0c\u7576\u6642\u505c\u5728Trenton St.\u548cCarrington Dr.\u4e00\u689d\u6b7b\u8def\u4e0a\u3002\u8eca\u6c92\u6709\u9396\uff0c\u9470\u5319\u5728\u88cf\u9762\u3002 \u8b66\u65b9\u8a8d\u70baGabe\u662f\u88ab\u524d\u7537\u53cbMarshal Jones\u6bba\u5bb3\u30026\u67081\u65e5\uff0cMarshal Jones\u5728\u897f\u96c5\u5716\u90ca\u5340\u8207\u8b66\u65b9\u5c0d\u5cd9\u6642\u88ab\u6bba\u3002 Oakley\u8b66\u5bdf\u5c40\u9577Paul Beard\u7576\u6642\u8868\u793a\uff0c\u5c0dGabe\u7684\u641c\u67e5\u662f\u8a72\u5c40\u6b77\u53f2\u4e0a\u6700\u5927\u6848\u4ef6\u3002\u4ed6\u8868\u793a\uff0c\u4ed6\u5df2\u91cd\u65b0\u6307\u6d3e\u4eba\u54e1\u9032\u884c\u8abf\u67e5\uff0c\u4e26\u5f97\u5230\u8a31\u591a\u6a5f\u69cb\u5354\u52a9\uff0c\u7279\u5225\u662fAntioch\u8b66\u5bdf\u5c40\u7684\u5354\u52a9\u3002 7\u6708\uff0cGabe\u5bb6\u4eba\u7372\u5f97Jones\u624b\u5beb\u7684\u6307\u793a\uff0c\u8b93\u8abf\u67e5\u4eba\u54e1\u524d\u5f80Amador\u7e23Pioneer\u4e00\u500b\u5730\u5340\u3002\u641c\u6551\u4eba\u54e1\u4f7f\u7528\u641c\u5c4d\u72d7\u5c0d\u8a72\u5730\u5340\u5c55\u958b\u641c\u7d22\uff0c\u751a\u81f3\u6aa2\u67e5\u9644\u8fd1\u4f4f\u5b85\u548c\u4f01\u696d\u7684\u5316\u7cde\u6c60\u3002 \u8b66\u65b9\u7576\u6642\u8b49\u5be6Jones\u66fe\u5728\u8a72\u5730\u5340\u51fa\u73fe\u3002\u8abf\u67e5\u4eba\u54e1\u7a31\uff0c\u5728\u4f7f\u7528\u624b\u5beb\u6307\u793a\u548c\u95dc\u9589\u624b\u6a5f\u6642\uff0cJones\u8ff7\u8def\u4e86\uff0c\u4e0d\u5f97\u4e0d\u6253\u958b\u624b\u6a5f\u627e\u56de\u6b63\u78ba\u7684\u8def\u3002\u5c31\u5728\u90a3\u6642\uff0c\u4ed6\u5011\u78ba\u5b9a\u4e86\u4ed6\u7684\u8e64\u8de1\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2022\/11\/missing-oakley-gabepic.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2022\/11\/missing-oakley-gabepic.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2022\/11\/missing-oakley-gabepic.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":244253,"url":"https:\/\/newsforchinese.com\/v3\/2023\/08\/09\/%e5%a4%b1%e8%b9%a417%e6%ad%b2saratoga%e5%a5%b3%e5%ad%a9%e7%9a%84%e8%bb%8a%e8%a2%ab%e6%89%be%e5%88%b0\/","url_meta":{"origin":244476,"position":1},"title":"\u5931\u8e6417\u6b72Saratoga\u5973\u5b69\u7684\u8eca\u88ab\u627e\u5230","author":"Yingying","date":"August 9, 2023","format":false,"excerpt":"\u5728\u4e00\u540d17\u6b72Saratoga\u5973\u5b69\u5931\u8e64\u4e00\u500b\u591a\u6708\u5f8c\uff0c\u672c\u9031\u8abf\u67e5\u4eba\u54e1\u627e\u5230\u4e86\u5979\u7684\u8eca\u3002Katherine\u300cKatie\u300dSchneider\u6700\u5f8c\u4e00\u6b21\u9732\u9762\u662f\u57287\u67085\u65e5\u3002\u7576\u6642\uff0c\u5979\u96e2\u958b\u5bb6\uff0c\u958b\u8457\u4e00\u8f1b\u767d\u8272Honda Accord\u3002 \u9031\u4e00\uff0cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u8abf\u67e5\u4eba\u54e1\u767c\u73fe\uff0cSchneider\u7684Honda Accord\u88ab\u907a\u68c4\u5728Castle Rock State Park\u9644\u8fd1\u7684Skyline Boulevard\u4e0a\u3002\u8b66\u9577\u8fa6\u516c\u5ba4\u5beb\u9053\uff1a\u300c\u8eca\u4e0a\u6c92\u6709\u4eba\u3002\u300d \u4e00\u500b\u540d\u70ba\u300cFind Katie Schneider\u300d\u7684Instagram\u9801\u9762\u767c\u4f48\u4e86\u4e00\u689d\u6d88\u606f\uff0c\u5beb\u9053\uff1a\u300cSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u5df2\u627e\u5230\u4e86Honda Accord\u3002\u7136\u800c\uff0c\u4ed6\u5011\u4ecd\u5728\u52aa\u529b\u5c0b\u627eKatie\u3002\u7531\u65bc\u8abf\u67e5\u4ecd\u5728\u9032\u884c\u4e2d\uff0c\u6211\u5011\u76ee\u524d\u7121\u6cd5\u63d0\u4f9b\u66f4\u591a\u7d30\u7bc0\u3002\u300d \u8b66\u9577\u8fa6\u516c\u5ba4\u4ecd\u5728\u5c0b\u6c42\u516c\u773e\u5e6b\u52a9\uff0c\u4ee5\u5c0b\u627e\u9019\u540d\u5931\u8e64\u5c11\u5973\u3002\u4efb\u4f55\u4eba\u5982\u6709\u5979\u7684\u4e0b\u843d\uff0c\u8acb\u81f4\u96fb408-808-4500\u8207Santa Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u806f\u7e6b\u3002 \u64da\u5979\u7684\u5bb6\u4eba\uff0c Schneider\u5931\u8e64\u6642\u8eab\u4e0a\u6c92\u6709\u9322\uff0c\u4e5f\u6c92\u6709\u8eab\u4efd\u8b49\u3002\u5bb6\u4eba\u5beb\u9053\uff1a\u300c\u6211\u5011\u8a8d\u70ba\u5979\u4e0d\u51c6\u5099\u96e2\u958b\u592a\u4e45\u3002\u300d Schneider\u6709\u85cd\u8272\u773c\u775b\uff0c\u76f4\u5230\u4e2d\u80cc\u90e8\u7684\u91d1\u9aee\u3002\u5979\u8eab\u9ad85\u82f1\u5c3a5\u82f1\u5bf8\uff0c\u9ad4\u91cd\u7d04115\u78c5\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Missing-Saratoga-teen-Katherine-Schneiders-car-found-on-Skyline-Boulevard.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Missing-Saratoga-teen-Katherine-Schneiders-car-found-on-Skyline-Boulevard.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Missing-Saratoga-teen-Katherine-Schneiders-car-found-on-Skyline-Boulevard.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":244113,"url":"https:\/\/newsforchinese.com\/v3\/2023\/08\/06\/%e5%b0%91%e5%a5%b3%e5%a4%b1%e8%b9%a4%e4%b8%80%e5%80%8b%e6%9c%88-%e8%ad%a6%e6%96%b9%e8%ab%8b%e5%85%ac%e7%9c%be%e7%95%99%e6%84%8f\/","url_meta":{"origin":244476,"position":2},"title":"\u5c11\u5973\u5931\u8e64\u4e00\u500b\u6708 \u8b66\u65b9\u8acb\u516c\u773e\u7559\u610f","author":"Yingying","date":"August 6, 2023","format":false,"excerpt":"\u7063\u5340\u8b66\u65b9\u8acb\u516c\u773e\u7559\u610f\u4e00\u540d\u5df2\u7d93\u5931\u8e64\u4e00\u500b\u6708\u7684\u5c11\u5973\u3002 \u6839\u64daSanta Clara\u7e23\u8b66\u9577\u8fa6\u516c\u5ba4\u672c\u9031\u767c\u4f48\u7684\u65b0\u805e\u7a3f\uff0c17\u6b72Katherine Claire Schneider7\u67085\u65e5\u5931\u8e64\u3002\u6700\u5f8c\u88ab\u770b\u5230\u6642\uff0c\u9019\u540d\u4f4f\u5728Saratoga\u7684\u5c11\u5973\u99d5\u99db\u4e00\u8f1b\u5e36\u6709\u8272\u8eca\u7a97\u7684\u767d\u82722019 Honda Accord\u3002\u9019\u8f1b\u8eca\u52a0\u5dde\u724c\u7167\u865f\u78bc\u662f8KLK251\u3002 Schneider\u6709\u91d1\u8272\u76f4\u767c\u548c\u85cd\u8272\u773c\u775b\uff0c\u5931\u8e64\u6642\u7a7f\u9ed1\u8272\u896f\u886b\u548c\u9ed1\u8272\u8932\u5b50\uff0c\u4e26\u4f69\u6234\u91d1\u8272\u9805\u93c8\u3002\u5979\u8eab\u9ad85\u82f1\u5c3a5\u82f1\u5bf8\uff0c\u5979\u88ab\u7a31\u4f5c\u300cKatie\u300d\u3002\u8b66\u9577\u8fa6\u516c\u5ba4\u6c92\u6709\u63d0\u4f9b\u95dc\u65bc\u5979\u5931\u8e64\u60c5\u6cc1\u7684\u9032\u4e00\u6b65\u8cc7\u8a0a\uff0c\u4f46\u5979\u6bcd\u89aa\u7684\u4e00\u500b\u516c\u958bInstagram\u5e33\u6236\u7d93\u5e38\u767c\u4f48\u95dc\u65bcSchneider\u7684\u6d88\u606f\u3002 \u300c\u6211\u5011\u7acb\u5373\u5411\u57f7\u6cd5\u90e8\u9580\u5831\u544a\u4e86Katie\u7684\u5931\u8e64\uff0c\u5f8c\u7e8c\u9075\u5faa\u4e86\u4ed6\u5011\u7684\u6307\u5c0e\u548c\u6307\u793a\uff0c\u300d\u9019\u500b\u5e33\u6236\u9031\u516d\u767c\u6587\u7a31\u3002\u300c\u6211\u5011\u4e00\u76f4\u8207\u57f7\u6cd5\u90e8\u9580\u5bc6\u5207\u5408\u4f5c\uff0c\u6211\u5011\u63a8\u9072\u4e86\u516c\u958b\uff0c\u90e8\u5206\u539f\u56e0\u662f\u6211\u5011\u5e0c\u671b\u5c0a\u91cd\u4ed6\u5011\u70ba\u5c0b\u627eKatie\u6240\u505a\u7684\u52aa\u529b\u3002\u540c\u6642\uff0c\u7531\u65bcKatie\u662f\u4e00\u500b\u5bb3\u7f9e\u3001\u5167\u5411\u7684\u5b69\u5b50\uff0c\u5728\u76e1\u4e00\u5207\u52aa\u529b\u627e\u5230\u5979\u7684\u540c\u6642\uff0c\u8a66\u5716\u4fdd\u8b77\u5979\u7684\u96b1\u79c1\u3002\u300d \u5982\u6709\u8cc7\u8a0a\uff0c\u8acb\u81f4\u96fb408-808-4500\u8b66\u9577\u8fa6\u516c\u5ba4\u3002\u4e5f\u53ef\u533f\u540d\u64a5\u6253408-808-443\uff0c\u6216\u767c\u9001\u96fb\u5b50\u90f5\u4ef6\u81f3PIO@shf.sccgov.org\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Katherine-Claire-Schneider.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Katherine-Claire-Schneider.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Katherine-Claire-Schneider.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":153948,"url":"https:\/\/newsforchinese.com\/v3\/2018\/03\/29\/%e5%a4%b1%e8%b9%a4%e5%a5%bd%e8%90%8a%e5%a1%a2%e5%a5%b3%e6%a8%a1%e7%89%b9%e9%81%ba%e9%aa%b8%e5%9c%a8%e5%8c%97%e5%8a%a0%e5%b7%9e%e8%a2%ab%e7%99%bc%e7%8f%be\/","url_meta":{"origin":244476,"position":3},"title":"\u5931\u8e64\u597d\u840a\u5862\u5973\u6a21\u7279\u907a\u9ab8\u5728\u5317\u52a0\u5dde\u88ab\u767c\u73fe","author":"Yingying","date":"March 29, 2018","format":false,"excerpt":"\u7576\u5c40\u9031\u4e09\u8aaa\uff0c\u5728\u5317\u52a0\u5dde\u4e00\u500b\u6dfa\u5893\u7a74\u4e2d\u767c\u73fe\u7684\u4e00\u5177\u8150\u721b\u5c4d\u9ad4\u88ab\u8b49\u5be6\u5c6c\u65bc\u4e00\u4f4d\u597d\u840a\u5862\u5931\u8e64\u6a21\u7279\u3002\u4e0a\u9031\uff0c\u5979\u6b7b\u4ea1\u6848\u4ef6\u4e2d\u7684\u5acc\u7591\u4eba-\u4e5f\u5c31\u662f\u5979\u7684\u7537\u53cb-\u5728\u5f15\u9818\u8b66\u65b9\u8ffd\u6355\u5f8c\u81ea\u6bba\u8eab\u4ea1\u3002 \u5728\u52a0\u5ddeAuburn\uff0cPlacer County Morgue\u7684\u9a57\u5c4d\u8b49\u5be6\u6240\u767c\u73fe\u907a\u9ab8\u4f86\u81ea\u6d1b\u6749\u78ef\u5931\u8e64\u6a21\u727925\u6b72\u7684Adea Shabani\u3002\u52a0\u5ddeNevada\u7e23\u6cbb\u5b89\u8fa6\u516c\u5ba4\u8aaa\uff0c\u7d0b\u8eab\u5e6b\u52a9\u4e86\u907a\u9ab8\u7684\u8fa8\u8a8d\u3002 \u5118\u7ba1\u9a57\u5c4d\u5b98\u78ba\u5b9aShabani\u982d\u90e8\u906d\u53d7\u920d\u5668\u50b7\u5bb3\uff0c\u4f46\u76ee\u524d\u6c92\u6709\u5c07\u5176\u5217\u70ba\u6b7b\u4ea1\u539f\u56e0\uff0c\u6700\u7d42\u539f\u56e0\u78ba\u5b9a\u9084\u9700\u8981\u7b49\u5f85\u9032\u4e00\u6b65\u7684\u6bd2\u7406\u5b78\u548c\u7d44\u7e54\u5206\u6790\u3002\u5979\u8eab\u9ad4\u5176\u4ed6\u90e8\u4f4d\u6c92\u6709\u53d7\u5230\u4efb\u4f55\u56b4\u91cd\u5275\u50b7\u3002 \u907a\u9ab8\u5728Nevada\u7e23\u4e00\u8655\u88ab\u767c\u73fe\u4e4b\u969b\uff0cLAPD\u6b63\u5728\u8abf\u67e5Shabani\u5931\u8e64\u6848\u4ef6\u3002Shabani\u6700\u5f8c\u65bc2\u670823\u65e5\u5728Hollywood Boulevard\u548cFranklin Avnue\u4e4b\u9593\u7684Wilcox Avenue 1700\u865f\u88ab\u770b\u5230\u3002 \u9019\u4f4d\u5e74\u8f15\u4eba\u4f86\u6d1b\u6749\u78ef\u5df2\u7d93\u6709\u5169\u5e74\uff0c\u5f9e\u4e8b\u6f14\u85dd\u4e8b\u696d\u3002\u5979\u4f86\u81eaMacedonia(\u99ac\u5176\u9813)\u3002 Shabani\u5931\u8e64\u8abf\u67e5\u4e0a\u9031\u51fa\u73fe\u7a81\u8b8a\uff1a\u5acc\u7591\u4eba\u5f15\u9818\u8b66\u65b9\u5c55\u958b\u4e00\u5834\u8ffd\u8eca\uff0c\u6700\u7d42\u4ee5\u5acc\u7591\u4eba\u81ea\u6bba\u6536\u5834\u3002 \u9019\u540d\u81ea\u6bba\u7537\u5b50\u88ab\u78ba\u8a8d\u70ba33\u6b72Christopher Spotz\u7684\u5317\u597d\u840a\u5862\u7537\u5b50\u3002 \u8b66\u65b9\u5728\u9031\u4e8c\u65b0\u805e\u767c\u4f48\u6703\u4e0a\u7a31\uff0c\u5728Shabani\u6d88\u5931\u4e00\u6bb5\u6642\u9593\u5f8c\uff0cSpotz\u901a\u904e\u5f8b\u5e2b\u767c\u8868\u8072\u660e\u8aaa\uff0c\u4ed6\u548cShabani\u958b\u8eca\u5411\u5317\u884c\u9032\uff0c\u4ed6\u5011\u767c\u751f\u4e86\u722d\u5435\uff0c\u4ed6\u5728Santa Clarita\u8b93\u5979\u4e0b\u4e86\u8eca\u3002 \u8b66\u65b9\u8868\u793a\uff0c\u4ed6\u5011\u7121\u6cd5\u8b49\u5be6Spotz\u7684\u6558\u8ff0\uff0c\u4e26\u4e14\u8a8d\u70ba\u5b83\u4e0d\u662f\u771f\u7684\u3002 Shabani\u548cSpotz\u90fd\u66fe\u5728\u597d\u840a\u5862Stella Adler Academy of Acting and Theater\u5b78\u9662\u5b78\u7fd2\u3002","rel":"","context":"In &quot;Entertainment&quot;","block_context":{"text":"Entertainment","link":"https:\/\/newsforchinese.com\/v3\/category\/entertainment\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/03\/missing-model.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/03\/missing-model.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/03\/missing-model.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":164392,"url":"https:\/\/newsforchinese.com\/v3\/2018\/11\/27\/camp-fire%e9%81%87%e9%9b%a388%e4%ba%ba-%e5%a4%b1%e8%b9%a4203%e4%ba%ba\/","url_meta":{"origin":244476,"position":4},"title":"Camp Fire\u9047\u96e388\u4eba\u00a0\u5931\u8e64203\u4eba","author":"Yingying","date":"November 27, 2018","format":false,"excerpt":"\u5317\u52a0\u5dde\u4e00\u4f4d\u8b66\u9577\u8aaa\uff0c\u9031\u4e00\u6c92\u6709\u767c\u73fe\u5176\u4ed6\u907a\u9ab8\uff0c\u4f46\u662f\u91ce\u706b\u7684\u6b7b\u4ea1\u4eba\u6578\u4e0a\u5347\u523088\u4eba\uff0c\u56e0\u70ba\u8abf\u67e5\u4eba\u54e1\u78ba\u5b9a\u539f\u6307\u70ba\u5c6c\u65bc\u5169\u4eba\u7684\u907a\u9ab8\u5be6\u969b\u4e0a\u5c6c\u65bc\u4e09\u4eba\u3002 Butte\u7e23\u8b66\u9577\u00a0Kory Honea\u9031\u4e00\u8868\u793a\uff0c\u5728\u5e2d\u6372San Francisco\u5317140\u82f1\u91cc\u8fb2\u6751\u5730\u5340\u7684Camp Fire\u88ab\u5b8c\u5168\u63a7\u5236\u5f8c\uff0c\u5931\u8e64\u8005\u540d\u55ae\u4ecd\u6709203\u4eba\u5728\u5217\u3002 \u806f\u90a6\u5167\u653f\u90e8\u9577Ryan Zinke\u8aaa\uff0c\u8207\u91ce\u706b\u6709\u95dc\u7684\u8cbb\u7528\u53ef\u80fd\u9ad8\u9054\u6578\u5341\u5104\u5143\u3002\u9031\u4e00\u56de\u5230Paradise\u93ae\u7684Zinke\u8aaa\uff0c\u4ed6\u5f9e\u4f86\u6c92\u6709\u76ee\u7779\u904e\u9019\u6a23\u7684\u7834\u58de\u3002 \u806f\u90a6\u7dca\u6025\u4e8b\u52d9\u7ba1\u7406\u5c40(Federal Emergency Management Agency)\u4e00\u540d\u5b98\u54e1\u9031\u4e00\u8868\u793a\uff0c\u806f\u90a6\u653f\u5e9c\u5df2\u5411\u5317\u52a0\u5dde\u56e0\u5927\u706b\u800c\u6d41\u96e2\u5931\u6240\u7684\u4eba\u6c11\u5206\u767c2000\u591a\u842c\u5143\u63f4\u52a9\uff0c\u6578\u767e\u540d\u641c\u6551\u4eba\u54e1\u4ecd\u5728\u5c0b\u627e\u66f4\u591a\u4eba\u985e\u907a\u9ab8\u3002 FEMA\u767c\u8a00\u4ebaFrank Mansell\u544a\u8a34The Associated Press\uff0c\u67091550\u842c\u5143\u7528\u65bc\u4f4f\u623f\u63f4\u52a9\uff0c\u5176\u4e2d\u5305\u62ec\u65c5\u9928\u623f\u9593\u8d08\u5238\u3002\u4ed6\u5728Chico\u5e02\u63a5\u53d7\u63a1\u8a2a\u6642\u8aaa\uff0c\u6551\u707d\u5de5\u4f5c\u9084\u8655\u65bc\u65e9\u671f\u968e\u6bb5\uff0c\u4f46\u8a31\u591a\u4eba\u6700\u7d42\u5c07\u5728\u62d6\u8eca\u6216\u516c\u5bd3\u4e2d\u9577\u671f\u5c45\u4f4f\u3002 \u4ed6\u9084\u8aaa\uff0cFEMA\u9084\u64a5\u6b3e500\u842c\u5143\u8aac\u660e\u89e3\u6c7a\u5176\u4ed6\u9700\u8981\uff0c\u5305\u62ec\u63d0\u4f9b\u55aa\u846c\u8cbb\u7528\u3002 Mansell\u8aaa\uff0c\u5927\u7d04\u670917000\u4eba\u5728FEMA\u767b\u8a18\uff0c\u8a72\u6a5f\u69cb\u5c07\u6aa2\u67e5\u4fdd\u96aa\u3001\u8cc7\u7522\u548c\u5176\u4ed6\u56e0\u7d20\uff0c\u4ee5\u78ba\u5b9a\u4ed6\u5011\u6709\u8cc7\u683c\u7372\u5f97\u591a\u5c11\u63f4\u52a9\u3002 Butte\u7e23\u8b66\u9577Kory Honea\u8aaa\uff0c\u4e0b\u843d\u4e0d\u660e\u4eba\u54e1\u540d\u55ae\u4e0a\u7684\u4eba\u6578\u5df2\u5f9e1300\u4eba\u9ad8\u9ede\u964d\u81f3\u9031\u4e00\u7684200\u591a\u4eba\u3002\u4ed6\u8aaa\uff0c\u641c\u5c0b\u5931\u8e64\u548c\u9047\u96e3\u8005\u7684\u5fd7\u9858\u8005\u4eba\u6578\u5df2\u5f9e\u9031\u65e5500\u4eba\u6e1b\u5c11\u5230\u9031\u4e00\u7684200\u4eba\uff0c\u56e0\u70ba\u8a31\u591a\u88ab\u5931\u8e64\u7684\u4eba\u5728\u9031\u672b\u88ab\u767c\u73fe\u3002 \u300c\u6211\u5011\u53d6\u5f97\u4e86\u5f88\u5927\u9032\u5c55\uff0c\u300dHonea\u8aaa\u3002 \u806f\u90a6\u8fb2\u696d\u90e8\u9577Sonny\u00a0Perdue\u8207Zinke\u4e00\u8d77\u63a2\u8a2a\u4e86Paradise\u3002Perdue\u5efa\u8b70\u5f9e\u9644\u8fd1Plumas\u570b\u5bb6\u68ee\u6797\u7372\u5f97\u6350\u8d08\u6728\u6750\u91cd\u5efaParadise\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/11\/camp-fire-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/11\/camp-fire-2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/11\/camp-fire-2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":154930,"url":"https:\/\/newsforchinese.com\/v3\/2018\/04\/21\/san-mateo%e7%b8%a3%e9%80%b1%e6%9c%ab%e8%88%89%e8%be%a6%e9%a6%96%e6%ac%a1missing-persons-day\/","url_meta":{"origin":244476,"position":5},"title":"San Mateo\u7e23\u9031\u672b\u8209\u8fa6\u9996\u6b21Missing Persons Day","author":"Yingying","date":"April 21, 2018","format":false,"excerpt":"San Mateo\u7e23\u672c\u9031\u672b\u8209\u8fa6\u9996\u6b21Missing Persons Day(\u5931\u8e64\u4eba\u54e1\u65e5)\uff0c\u5e0c\u671b\u80fd\u5e6b\u52a9\u7834\u89e3\u4e00\u4e9b\u672a\u89e3\u6c7a\u6848\u4ef6\u3002 \u6709\u5931\u8e64\u5bb6\u5ead\u6210\u54e1\u7684\u4eba\u53ef\u4ee5\u63d0\u4ea4\u4ed6\u5011\u7684DNA\u6216\u4ed6\u5011\u5931\u8e64\u89aa\u5c6c\u7684DNA\uff0c\u4ee5\u5e6b\u52a9\u78ba\u5b9a\u8a72\u7e2380\u500b\u672a\u78ba\u8a8d\u907a\u9ab8\u4e2d\u67d0\u4e00\u500b\uff0c\u4ee5\u53ca\u5e6b\u52a9\u89e3\u6c7a\u5168\u7f8e\u5931\u8e64\u4eba\u54e1\u6848\u4ef6\u3002 \u9019\u88e1\u6709\u4e00\u8d77Brisbane\u8b66\u65b9\u5e0c\u671b\u89e3\u6c7a\u7684\u6848\u4ef6\uff1a\u4e00\u540d\u7537\u5b50\u57282012\u5e74\u5f15\u9818\u4ed6\u5011\u627e\u5230\u5230\u4e00\u540d\u5973\u5b50\u907a\u9ab8\uff0c\u8aaa\u4ed6\u767c\u73fe\u4e86\u9019\u4e9b\u907a\u9ab8\u3002 \u9019\u500b\u9031\u672b\u8b66\u65b9\u5e0c\u671b\u4ed6\u5011\u80fd\u5728\u9019\u8d77\u6848\u5b50\u4e0a\u627e\u5230\u7dda\u7d22\u3002\u4ed6\u5011\u4ecd\u7136\u4e0d\u77e5\u9053\u5979\u7684\u8eab\u4efd\u3002\u5979\u5e74\u9f61\u572828\u523030\u6b72\u4e4b\u9593\uff0c\u4ed6\u5011\u8a8d\u70ba\u5979\u53ef\u80fd\u57282001\u52302008\u6b72\u4e4b\u9593\u6b7b\u53bb\u3002 \u300c\u9019\u662f\u67d0\u4eba\u7684\u6bcd\u89aa\u3001\u59d0\u59b9\u3001\u597d\u670b\u53cb\uff0c\u6211\u76f8\u4fe1\u5979\u7684\u907a\u9ab8\u5e0c\u671b\u80fd\u5b89\u606f\uff0c\u300dBrisbane\u8b66\u5bdf\u5c40\u7684Michelle Moneda\u8aaa\u3002 \u5b98\u54e1\u5011\u6b63\u52aa\u529b\u9f13\u52f5\u793e\u5340\u53c3\u52a0\u9019\u9805\u6d3b\u52d5\uff0c\u7528\u7167\u7247\u3001X\u5149\u548c\u4ed6\u5011\u8a8d\u70ba\u53ef\u80fd\u6703\u5e6b\u52a9\u7834\u6848\u7684\u5176\u4ed6\u6771\u897f\u4f86\u5e6b\u52a9\u8b58\u5225\u6216\u5831\u544a\u5931\u8e64\u7684\u89aa\u4eba\u3002 San Mateo\u7e23\u76ee\u524d\u6709440\u8d77\u4eba\u53e3\u5931\u8e64\u6848\u4ef6\u3002","rel":"","context":"In &quot;\u5730\u65b9\u65b0\u805e&quot;","block_context":{"text":"\u5730\u65b9\u65b0\u805e","link":"https:\/\/newsforchinese.com\/v3\/category\/local\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/04\/missing-person-day.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/04\/missing-person-day.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/newsforchinese.com\/v3\/wp-content\/uploads\/2018\/04\/missing-person-day.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/newsforchinese.com\/v3\/wp-content\/uploads\/2023\/08\/Human-remains-belong-to-missing-Saratoga-teen-mom-says.jpg","_links":{"self":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts\/244476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/users\/1001022"}],"replies":[{"embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/comments?post=244476"}],"version-history":[{"count":2,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts\/244476\/revisions"}],"predecessor-version":[{"id":244479,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/posts\/244476\/revisions\/244479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/media\/244477"}],"wp:attachment":[{"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/media?parent=244476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/categories?post=244476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/tags?post=244476"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/newsforchinese.com\/v3\/wp-json\/wp\/v2\/series?post=244476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}